{"id":7144,"date":"2021-04-20T18:21:58","date_gmt":"2021-04-20T16:21:58","guid":{"rendered":"https:\/\/www.fayence-steinzeug-vogt.de\/?page_id=7144"},"modified":"2026-01-30T18:07:15","modified_gmt":"2026-01-30T17:07:15","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/www.fayence-steinzeug-vogt.de\/de\/datenschutzerklaerung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"<h1>\n<p class=\"uk-article-title\">Datenschutzerkl\u00e4rung<\/p>\n<\/h1>\n<div>\n<div class=\"uk-margin-medium\" property=\"text\">\n<h2>Einleitung<\/h2>\n<p>Mit der folgenden Datenschutzerkl\u00e4rung m\u00f6chten wir Sie dar\u00fcber aufkl\u00e4ren, welche Arten Ihrer personenbezogenen Daten (nachfolgend auch kurz als \u201eDaten\u201c bezeichnet) wir zu welchen Zwecken und in welchem Umfang verarbeiten. Die Datenschutzerkl\u00e4rung gilt f\u00fcr alle von uns durchgef\u00fchrten Verarbeitungen personenbezogener Daten, sowohl im Rahmen der Erbringung unserer Leistungen als auch insbesondere auf unseren Webseiten, in mobilen Applikationen sowie innerhalb externer Onlinepr\u00e4senzen, wie z.B. unserer Social-Media-Profile (nachfolgend zusammenfassend bezeichnet als \u201eOnlineangebot\u201c).<\/p>\n<p>Die verwendeten Begriffe sind nicht geschlechtsspezifisch.<\/p>\n<p>Stand: 20. April 2021<\/p>\n<h2>Inhalts\u00fcbersicht<\/h2>\n<ul>\n<li><a href=\"https:\/\/stage.fayence-steinzeug-vogt.de\/de\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m14\">Einleitung<\/a><\/li>\n<li><a href=\"https:\/\/stage.fayence-steinzeug-vogt.de\/de\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m3\">Verantwortlicher<\/a><\/li>\n<li><a href=\"https:\/\/stage.fayence-steinzeug-vogt.de\/de\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#mOverview\">\u00dcbersicht der Verarbeitungen<\/a><\/li>\n<li><a href=\"https:\/\/stage.fayence-steinzeug-vogt.de\/de\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m13\">Ma\u00dfgebliche Rechtsgrundlagen<\/a><\/li>\n<li><a href=\"https:\/\/stage.fayence-steinzeug-vogt.de\/de\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m27\">Sicherheitsma\u00dfnahmen<\/a><\/li>\n<li><a href=\"https:\/\/stage.fayence-steinzeug-vogt.de\/de\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m134\">Einsatz von Cookies<\/a><\/li>\n<li><a href=\"https:\/\/stage.fayence-steinzeug-vogt.de\/de\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m225\">Bereitstellung des Onlineangebotes und Webhosting<\/a><\/li>\n<li><a href=\"https:\/\/stage.fayence-steinzeug-vogt.de\/de\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m104\">Blogs und Publikationsmedien<\/a><\/li>\n<li><a href=\"https:\/\/stage.fayence-steinzeug-vogt.de\/de\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m29\">Cloud-Dienste<\/a><\/li>\n<li><a href=\"https:\/\/stage.fayence-steinzeug-vogt.de\/de\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m17\">Newsletter und elektronische Benachrichtigungen<\/a><\/li>\n<li><a href=\"https:\/\/stage.fayence-steinzeug-vogt.de\/de\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m263\">Webanalyse, Monitoring und Optimierung<\/a><\/li>\n<li><a href=\"https:\/\/stage.fayence-steinzeug-vogt.de\/de\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m136\">Pr\u00e4senzen in sozialen Netzwerken (Social Media)<\/a><\/li>\n<li><a href=\"https:\/\/stage.fayence-steinzeug-vogt.de\/de\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m328\">Plugins und eingebettete Funktionen sowie Inhalte<\/a><\/li>\n<li><a href=\"https:\/\/stage.fayence-steinzeug-vogt.de\/de\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m12\">L\u00f6schung von Daten<\/a><\/li>\n<li><a href=\"https:\/\/stage.fayence-steinzeug-vogt.de\/de\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m15\">\u00c4nderung und Aktualisierung der Datenschutzerkl\u00e4rung<\/a><\/li>\n<li><a href=\"https:\/\/stage.fayence-steinzeug-vogt.de\/de\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m10\">Rechte der betroffenen Personen<\/a><\/li>\n<li><a href=\"https:\/\/stage.fayence-steinzeug-vogt.de\/de\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m42\">Begriffsdefinitionen<\/a><\/li>\n<\/ul>\n<h2 id=\"m3\">Verantwortlicher<\/h2>\n<p>Antiquit\u00e4ten im Rathaus<br \/>Peter Vogt<br \/>Marienplatz 8<br \/>80331 M\u00fcnchen<\/p>\n<p>Vertretungsberechtigte Personen: Peter Vogt.<\/p>\n<p>E-Mail-Adresse: verkauf(a)fayence-steinzeug-vogt.de.<\/p>\n<p>Telefon: 089 294132.<\/p>\n<p>Impressum: <a href=\"https:\/\/www.fayence-steinzeug-vogt.de\/de\/impressum\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/fayence-steinzeug-vogt.de\/impressum\/<\/a>.<\/p>\n<h2 id=\"mOverview\">\u00dcbersicht der Verarbeitungen<\/h2>\n<p>Die nachfolgende \u00dcbersicht fasst die Arten der verarbeiteten Daten und die Zwecke ihrer Verarbeitung zusammen und verweist auf die betroffenen Personen.<\/p>\n<h3>Arten der verarbeiteten Daten<\/h3>\n<ul>\n<li>Event-Daten (Facebook) (\u201eEvent-Daten\u201c sind Daten, die z. B. via Facebook-Pixel (via Apps oder auf anderen Wegen) von uns an Facebook \u00fcbermittelt werden k\u00f6nnen und sich auf Personen oder deren Handlungen beziehen; Zu den Daten geh\u00f6ren z. B. Angaben \u00fcber Besuche auf Websites, Interaktionen mit Inhalten, Funktionen, Installationen von Apps, K\u00e4ufe von Produkten, etc.; die Event-Daten werden zwecks Bildung von Zielgruppen f\u00fcr Inhalte und Werbeinformationen (Custom Audiences) verarbeitet; Event Daten beinhalten nicht die eigentlichen Inhalte (wie z. B. verfasste Kommentare), keine Login-Informationen und keine Kontaktinformationen (also keine Namen, E-Mail-Adressen und Telefonnummern). Event Daten werden durch Facebook nach maximal zwei Jahren gel\u00f6scht, die aus ihnen gebildeten Zielgruppen mit der L\u00f6schung unseres Facebook-Kontos).<\/li>\n<li>Bestandsdaten (z.B. Namen, Adressen).<\/li>\n<li>Inhaltsdaten (z.B. Eingaben in Onlineformularen).<\/li>\n<li>Kontaktdaten (z.B. E-Mail, Telefonnummern).<\/li>\n<li>Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen).<\/li>\n<li>Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten).<\/li>\n<\/ul>\n<h3>Kategorien betroffener Personen<\/h3>\n<ul>\n<li>Besch\u00e4ftigte (z.B. Angestellte, Bewerber, ehemalige Mitarbeiter).<\/li>\n<li>Interessenten.<\/li>\n<li>Kommunikationspartner.<\/li>\n<li>Kunden.<\/li>\n<li>Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\/li>\n<\/ul>\n<h3>Zwecke der Verarbeitung<\/h3>\n<ul>\n<li>Bereitstellung unseres Onlineangebotes und Nutzerfreundlichkeit.<\/li>\n<li>B\u00fcro- und Organisationsverfahren.<\/li>\n<li>Direktmarketing (z.B. per E-Mail oder postalisch).<\/li>\n<li>Feedback (z.B. Sammeln von Feedback via Online-Formular).<\/li>\n<li>Marketing.<\/li>\n<li>Kontaktanfragen und Kommunikation.<\/li>\n<li>Profile mit nutzerbezogenen Informationen (Erstellen von Nutzerprofilen).<\/li>\n<li>Reichweitenmessung (z.B. Zugriffsstatistiken, Erkennung wiederkehrender Besucher).<\/li>\n<li>Sicherheitsma\u00dfnahmen.<\/li>\n<li>Erbringung vertragliche Leistungen und Kundenservice.<\/li>\n<\/ul>\n<h3 id=\"m13\">Ma\u00dfgebliche Rechtsgrundlagen<\/h3>\n<p>Nachfolgend erhalten Sie einen \u00dcberblick \u00fcber die Rechtsgrundlagen der DSGVO, die wir der Verarbeitung personenbezogener Daten zugrunde legen. Bitte beachten Sie, dass zus\u00e4tzlich zu den Bestimmungen der DSGVO, nationale Datenschutzbestimmungen Ihres oder unseres Wohnsitz-, bzw. Sitzlandes zur Anwendung kommen k\u00f6nnen. Sollten ferner im Einzelfall speziellere Rechtsgrundlagen ma\u00dfgeblich sein, teilen wir Ihnen diese in der Datenschutzerkl\u00e4rung mit.<\/p>\n<ul>\n<li><strong>Einwilligung (Art. 6 Abs. 1 S. 1 lit. a. DSGVO)<\/strong> \u2013 Die betroffene Person hat ihre Einwilligung in die Verarbeitung der sie betreffenden personenbezogenen Daten f\u00fcr einen spezifischen Zweck oder mehrere bestimmte Zwecke gegeben.<\/li>\n<li><strong>Vertragserf\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO)<\/strong> \u2013 Die Verarbeitung ist f\u00fcr die Erf\u00fcllung eines Vertrags, dessen Vertragspartei die betroffene Person ist, oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich, die auf Anfrage der betroffenen Person erfolgen.<\/li>\n<li><strong>Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO)<\/strong> \u2013 Die Verarbeitung ist zur Wahrung der berechtigten Interessen des Verantwortlichen oder eines Dritten erforderlich, sofern nicht die Interessen oder Grundrechte und Grundfreiheiten der betroffenen Person, die den Schutz personenbezogener Daten erfordern, \u00fcberwiegen.<\/li>\n<\/ul>\n<p><strong>Nationale Datenschutzregelungen in Deutschland<\/strong>: Zus\u00e4tzlich zu den Datenschutzregelungen der Datenschutz-Grundverordnung gelten nationale Regelungen zum Datenschutz in Deutschland. Hierzu geh\u00f6rt insbesondere das Gesetz zum Schutz vor Missbrauch personenbezogener Daten bei der Datenverarbeitung (Bundesdatenschutzgesetz \u2013 BDSG). Das BDSG enth\u00e4lt insbesondere Spezialregelungen zum Recht auf Auskunft, zum Recht auf L\u00f6schung, zum Widerspruchsrecht, zur Verarbeitung besonderer Kategorien personenbezogener Daten, zur Verarbeitung f\u00fcr andere Zwecke und zur \u00dcbermittlung sowie automatisierten Entscheidungsfindung im Einzelfall einschlie\u00dflich Profiling. Des Weiteren regelt es die Datenverarbeitung f\u00fcr Zwecke des Besch\u00e4ftigungsverh\u00e4ltnisses (\u00a7 26 BDSG), insbesondere im Hinblick auf die Begr\u00fcndung, Durchf\u00fchrung oder Beendigung von Besch\u00e4ftigungsverh\u00e4ltnissen sowie die Einwilligung von Besch\u00e4ftigten. Ferner k\u00f6nnen Landesdatenschutzgesetze der einzelnen Bundesl\u00e4nder zur Anwendung gelangen.<\/p>\n<h2 id=\"m27\">Sicherheitsma\u00dfnahmen<\/h2>\n<p>Wir treffen nach Ma\u00dfgabe der gesetzlichen Vorgaben unter Ber\u00fccksichtigung des Stands der Technik, der Implementierungskosten und der Art, des Umfangs, der Umst\u00e4nde und der Zwecke der Verarbeitung sowie der unterschiedlichen Eintrittswahrscheinlichkeiten und des Ausma\u00dfes der Bedrohung der Rechte und Freiheiten nat\u00fcrlicher Personen geeignete technische und organisatorische Ma\u00dfnahmen, um ein dem Risiko angemessenes Schutzniveau zu gew\u00e4hrleisten.<\/p>\n<p>Zu den Ma\u00dfnahmen geh\u00f6ren insbesondere die Sicherung der Vertraulichkeit, Integrit\u00e4t und Verf\u00fcgbarkeit von Daten durch Kontrolle des physischen und elektronischen Zugangs zu den Daten als auch des sie betreffenden Zugriffs, der Eingabe, der Weitergabe, der Sicherung der Verf\u00fcgbarkeit und ihrer Trennung. Des Weiteren haben wir Verfahren eingerichtet, die eine Wahrnehmung von Betroffenenrechten, die L\u00f6schung von Daten und Reaktionen auf die Gef\u00e4hrdung der Daten gew\u00e4hrleisten. Ferner ber\u00fccksichtigen wir den Schutz personenbezogener Daten bereits bei der Entwicklung bzw. Auswahl von Hardware, Software sowie Verfahren entsprechend dem Prinzip des Datenschutzes, durch Technikgestaltung und durch datenschutzfreundliche Voreinstellungen.<\/p>\n<p><strong>SSL-Verschl\u00fcsselung (https)<\/strong>: Um Ihre via unser Online-Angebot \u00fcbermittelten Daten zu sch\u00fctzen, nutzen wir eine SSL-Verschl\u00fcsselung. Sie erkennen derart verschl\u00fcsselte Verbindungen an dem Pr\u00e4fix https:\/\/ in der Adresszeile Ihres Browsers.<\/p>\n<h2 id=\"m134\">Einsatz von Cookies<\/h2>\n<p>Cookies sind Textdateien, die Daten von besuchten Websites oder Domains enthalten und von einem Browser auf dem Computer des Benutzers gespeichert werden. Ein Cookie dient in erster Linie dazu, die Informationen \u00fcber einen Benutzer w\u00e4hrend oder nach seinem Besuch innerhalb eines Onlineangebotes zu speichern. Zu den gespeicherten Angaben k\u00f6nnen z.B. die Spracheinstellungen auf einer Webseite, der Loginstatus, ein Warenkorb oder die Stelle, an der ein Video geschaut wurde, geh\u00f6ren. Zu dem Begriff der Cookies z\u00e4hlen wir ferner andere Technologien, die die gleichen Funktionen wie Cookies erf\u00fcllen (z.B., wenn Angaben der Nutzer anhand pseudonymer Onlinekennzeichnungen gespeichert werden, auch als \u201eNutzer-IDs\u201c bezeichnet)<\/p>\n<p><strong>Die folgenden Cookie-Typen und Funktionen werden unterschieden:<\/strong><\/p>\n<ul>\n<li><strong>Tempor\u00e4re Cookies (auch: Session- oder Sitzungs-Cookies):<\/strong>\u00a0Tempor\u00e4re Cookies werden sp\u00e4testens gel\u00f6scht, nachdem ein Nutzer ein Online-Angebot verlassen und seinen Browser geschlossen hat.<\/li>\n<li><strong>Permanente Cookies:<\/strong>\u00a0Permanente Cookies bleiben auch nach dem Schlie\u00dfen des Browsers gespeichert. So kann beispielsweise der Login-Status gespeichert oder bevorzugte Inhalte direkt angezeigt werden, wenn der Nutzer eine Website erneut besucht. Ebenso k\u00f6nnen die Interessen von Nutzern, die zur Reichweitenmessung oder zu Marketingzwecken verwendet werden, in einem solchen Cookie gespeichert werden.<\/li>\n<li><strong>First-Party-Cookies:<\/strong>\u00a0First-Party-Cookies werden von uns selbst gesetzt.<\/li>\n<li><strong>Third-Party-Cookies (auch: Drittanbieter-Cookies)<\/strong>: Drittanbieter-Cookies werden haupts\u00e4chlich von Werbetreibenden (sog. Dritten) verwendet, um Benutzerinformationen zu verarbeiten.<\/li>\n<li><strong>Notwendige (auch: essentielle oder unbedingt erforderliche) Cookies:<\/strong> Cookies k\u00f6nnen zum einen f\u00fcr den Betrieb einer Webseite unbedingt erforderlich sein (z.B. um Logins oder andere Nutzereingaben zu speichern oder aus Gr\u00fcnden der Sicherheit).<\/li>\n<li><strong>Statistik-, Marketing- und Personalisierungs-Cookies<\/strong>: Ferner werden Cookies im Regelfall auch im Rahmen der Reichweitenmessung eingesetzt sowie dann, wenn die Interessen eines Nutzers oder sein Verhalten (z.B. Betrachten bestimmter Inhalte, Nutzen von Funktionen etc.) auf einzelnen Webseiten in einem Nutzerprofil gespeichert werden. Solche Profile dienen dazu, den Nutzern z.B. Inhalte anzuzeigen, die ihren potentiellen Interessen entsprechen. Dieses Verfahren wird auch als \u201eTracking\u201c, d.h., Nachverfolgung der potentiellen Interessen der Nutzer bezeichnet. Soweit wir Cookies oder \u201eTracking\u201c-Technologien einsetzen, informieren wir Sie gesondert in unserer Datenschutzerkl\u00e4rung oder im Rahmen der Einholung einer Einwilligung.<\/li>\n<\/ul>\n<p><strong>Hinweise zu Rechtsgrundlagen:<\/strong> Auf welcher Rechtsgrundlage wir Ihre personenbezogenen Daten mit Hilfe von Cookies verarbeiten, h\u00e4ngt davon ab, ob wir Sie um eine Einwilligung bitten. Falls dies zutrifft und Sie in die Nutzung von Cookies einwilligen, ist die Rechtsgrundlage der Verarbeitung Ihrer Daten die erkl\u00e4rte Einwilligung. Andernfalls werden die mithilfe von Cookies verarbeiteten Daten auf Grundlage unserer berechtigten Interessen (z.B. an einem betriebswirtschaftlichen Betrieb unseres Onlineangebotes und dessen Verbesserung) verarbeitet oder, wenn der Einsatz von Cookies erforderlich ist, um unsere vertraglichen Verpflichtungen zu erf\u00fcllen.<\/p>\n<p><strong>Speicherdauer: <\/strong>Sofern wir Ihnen keine expliziten Angaben zur Speicherdauer von permanenten Cookies mitteilen (z. B. im Rahmen eines sog. Cookie-Opt-Ins), gehen Sie bitte davon aus, dass die Speicherdauer bis zu zwei Jahre betragen kann.<\/p>\n<p><strong>Allgemeine Hinweise zum Widerruf und Widerspruch (Opt-Out):<\/strong> Abh\u00e4ngig davon, ob die Verarbeitung auf Grundlage einer Einwilligung oder gesetzlichen Erlaubnis erfolgt, haben Sie jederzeit die M\u00f6glichkeit, eine erteilte Einwilligung zu widerrufen oder der Verarbeitung Ihrer Daten durch Cookie-Technologien zu widersprechen (zusammenfassend als \u201eOpt-Out\u201c bezeichnet). Sie k\u00f6nnen Ihren Widerspruch zun\u00e4chst mittels der Einstellungen Ihres Browsers erkl\u00e4ren, z.B., indem Sie die Nutzung von Cookies deaktivieren (wobei hierdurch auch die Funktionsf\u00e4higkeit unseres Onlineangebotes eingeschr\u00e4nkt werden kann). Ein Widerspruch gegen den Einsatz von Cookies zu Zwecken des Onlinemarketings kann auch mittels einer Vielzahl von Diensten, vor allem im Fall des Trackings, \u00fcber die Webseiten <a href=\"https:\/\/optout.aboutads.info\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/optout.aboutads.info<\/a> und <a href=\"https:\/\/www.youronlinechoices.com\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.youronlinechoices.com\/<\/a> erkl\u00e4rt werden. Daneben k\u00f6nnen Sie weitere Widerspruchshinweise im Rahmen der Angaben zu den eingesetzten Dienstleistern und Cookies erhalten.<\/p>\n<p><strong>Verarbeitung von Cookie-Daten auf Grundlage einer Einwilligung<\/strong>: Wir setzen ein Verfahren zum Cookie-Einwilligungs-Management ein, in dessen Rahmen die Einwilligungen der Nutzer in den Einsatz von Cookies, bzw. der im Rahmen des Cookie-Einwilligungs-Management-Verfahrens genannten Verarbeitungen und Anbieter eingeholt sowie von den Nutzern verwaltet und widerrufen werden k\u00f6nnen. Hierbei wird die Einwilligungserkl\u00e4rung gespeichert, um deren Abfrage nicht erneut wiederholen zum m\u00fcssen und die Einwilligung entsprechend der gesetzlichen Verpflichtung nachweisen zu k\u00f6nnen. Die Speicherung kann serverseitig und\/oder in einem Cookie (sogenanntes Opt-In-Cookie, bzw. mithilfe vergleichbarer Technologien) erfolgen, um die Einwilligung einem Nutzer, bzw. dessen Ger\u00e4t zuordnen zu k\u00f6nnen. Vorbehaltlich individueller Angaben zu den Anbietern von Cookie-Management-Diensten, gelten die folgenden Hinweise: Die Dauer der Speicherung der Einwilligung kann bis zu zwei Jahren betragen. Hierbei wird ein pseudonymer Nutzer-Identifikator gebildet und mit dem Zeitpunkt der Einwilligung, Angaben zur Reichweite der Einwilligung (z. B. welche Kategorien von Cookies und\/oder Diensteanbieter) sowie dem Browser, System und verwendeten Endger\u00e4t gespeichert.<\/p>\n<p>Cookie-Einstellungen\/ -Widerspruchsm\u00f6glichkeit:<\/p>\n<ul>\n<li><strong>Verarbeitete Datenarten:<\/strong> Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen).<\/li>\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Einwilligung (Art. 6 Abs. 1 S. 1 lit. a. DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO).<\/li>\n<\/ul>\n<p><strong>Eingesetzte Dienste und Diensteanbieter:<\/strong><\/p>\n<ul>\n<li><strong>Cookiebot:<\/strong> Cookie-Einwilligungs-Management; Dienstanbieter: Cybot A\/S, Havnegade 39, 1058 Kopenhagen, D\u00e4nemark; Website: <a href=\"https:\/\/www.cookiebot.com\/de\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.cookiebot.com\/de<\/a>; Datenschutzerkl\u00e4rung: <a href=\"https:\/\/www.cookiebot.com\/de\/privacy-policy\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.cookiebot.com\/de\/privacy-policy\/<\/a>; Gespeicherte Daten (auf dem Server des Dienstleisters): Die IP-Nummer des Nutzers in anonymisierter Form (die letzten drei Ziffern werden auf 0 gesetzt), Datum und Uhrzeit der Zustimmung, Browserangaben, die URL, von der die Zustimmung gesendet wurde, Ein anonymer, zuf\u00e4lliger und verschl\u00fcsselter Schl\u00fcsselwert; der Einwilligungsstatus des Nutzers.<\/li>\n<\/ul>\n<h2 id=\"m225\">Bereitstellung des Onlineangebotes und Webhosting<\/h2>\n<p>Um unser Onlineangebot sicher und effizient bereitstellen zu k\u00f6nnen, nehmen wir die Leistungen von einem oder mehreren Webhosting-Anbietern in Anspruch, von deren Servern (bzw. von ihnen verwalteten Servern) das Onlineangebot abgerufen werden kann. Zu diesen Zwecken k\u00f6nnen wir Infrastruktur- und Plattformdienstleistungen, Rechenkapazit\u00e4t, Speicherplatz und Datenbankdienste sowie Sicherheitsleistungen und technische Wartungsleistungen in Anspruch nehmen.<\/p>\n<p>Zu den im Rahmen der Bereitstellung des Hostingangebotes verarbeiteten Daten k\u00f6nnen alle die Nutzer unseres Onlineangebotes betreffenden Angaben geh\u00f6ren, die im Rahmen der Nutzung und der Kommunikation anfallen. Hierzu geh\u00f6ren regelm\u00e4\u00dfig die IP-Adresse, die notwendig ist, um die Inhalte von Onlineangeboten an Browser ausliefern zu k\u00f6nnen, und alle innerhalb unseres Onlineangebotes oder von Webseiten get\u00e4tigten Eingaben.<\/p>\n<p><strong>E-Mail-Versand und -Hosting<\/strong>: Die von uns in Anspruch genommenen Webhosting-Leistungen umfassen ebenfalls den Versand, den Empfang sowie die Speicherung von E-Mails. Zu diesen Zwecken werden die Adressen der Empf\u00e4nger sowie Absender als auch weitere Informationen betreffend den E-Mailversand (z.B. die beteiligten Provider) sowie die Inhalte der jeweiligen E-Mails verarbeitet. Die vorgenannten Daten k\u00f6nnen ferner zu Zwecken der Erkennung von SPAM verarbeitet werden. Wir bitten darum, zu beachten, dass E-Mails im Internet grunds\u00e4tzlich nicht verschl\u00fcsselt versendet werden. Im Regelfall werden E-Mails zwar auf dem Transportweg verschl\u00fcsselt, aber (sofern kein sogenanntes Ende-zu-Ende-Verschl\u00fcsselungsverfahren eingesetzt wird) nicht auf den Servern, von denen sie abgesendet und empfangen werden. Wir k\u00f6nnen daher f\u00fcr den \u00dcbertragungsweg der E-Mails zwischen dem Absender und dem Empfang auf unserem Server keine Verantwortung \u00fcbernehmen.<\/p>\n<p><strong>Erhebung von Zugriffsdaten und Logfiles<\/strong>: Wir selbst (bzw. unser Webhostinganbieter) erheben Daten zu jedem Zugriff auf den Server (sogenannte Serverlogfiles). Zu den Serverlogfiles k\u00f6nnen die Adresse und Name der abgerufenen Webseiten und Dateien, Datum und Uhrzeit des Abrufs, \u00fcbertragene Datenmengen, Meldung \u00fcber erfolgreichen Abruf, Browsertyp nebst Version, das Betriebssystem des Nutzers, Referrer URL (die zuvor besuchte Seite) und im Regelfall IP-Adressen und der anfragende Provider geh\u00f6ren.<\/p>\n<p>Die Serverlogfiles k\u00f6nnen zum einen zu Zwecken der Sicherheit eingesetzt werden, z.B., um eine \u00dcberlastung der Server zu vermeiden (insbesondere im Fall von missbr\u00e4uchlichen Angriffen, sogenannten DDoS-Attacken) und zum anderen, um die Auslastung der Server und ihre Stabilit\u00e4t sicherzustellen.<\/p>\n<ul>\n<li><strong>Verarbeitete Datenarten:<\/strong> Inhaltsdaten (z.B. Eingaben in Onlineformularen), Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen).<\/li>\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> Bereitstellung unseres Onlineangebotes und Nutzerfreundlichkeit.<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO).<\/li>\n<\/ul>\n<p><strong>Eingesetzte Dienste und Diensteanbieter:<\/strong><\/p>\n<ul>\n<li><strong>goneo:<\/strong> Leistungen auf dem Gebiet der Bereitstellung von informationstechnischer Infrastruktur und verbundenen Dienstleistungen (z.B. Speicherplatz und\/oder Rechenkapazit\u00e4ten); Dienstanbieter: goneo Internet GmbH, Dresdener Stra\u00dfe 18, 32423 Minden, Deutschland; Website: <a href=\"https:\/\/www.goneo.de\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.goneo.de<\/a>; Datenschutzerkl\u00e4rung: <a href=\"https:\/\/www.goneo.de\/hilfe_kontakt\/datenschutz.html\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.goneo.de\/hilfe_kontakt\/datenschutz.html<\/a>.<\/li>\n<\/ul>\n<h2 id=\"m104\">Blogs und Publikationsmedien<\/h2>\n<p>Wir nutzen Blogs oder vergleichbare Mittel der Onlinekommunikation und Publikation (nachfolgend \u201ePublikationsmedium\u201c). Die Daten der Leser werden f\u00fcr die Zwecke des Publikationsmediums nur insoweit verarbeitet, als es f\u00fcr dessen Darstellung und die Kommunikation zwischen Autoren und Lesern oder aus Gr\u00fcnden der Sicherheit erforderlich ist. Im \u00dcbrigen verweisen wir auf die Informationen zur Verarbeitung der Besucher unseres Publikationsmediums im Rahmen dieser Datenschutzhinweise.<\/p>\n<ul>\n<li><strong>Verarbeitete Datenarten:<\/strong> Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail, Telefonnummern), Inhaltsdaten (z.B. Eingaben in Onlineformularen), Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen).<\/li>\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> Erbringung vertragliche Leistungen und Kundenservice, Feedback (z.B. Sammeln von Feedback via Online-Formular), Sicherheitsma\u00dfnahmen.<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Vertragserf\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO).<\/li>\n<\/ul>\n<p><strong>Eingesetzte Dienste und Diensteanbieter:<\/strong><\/p>\n<ul>\n<li><strong>UpdraftPlus:<\/strong> Backup-Software und Backup-Speicherung; Dienstanbieter: Simba Hosting Ltd., 11, Barringer Way, St. Neots, Cambs., PE19 1LW, GB; Website: <a href=\"https:\/\/updraftplus.com\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/updraftplus.com\/<\/a>; Datenschutzerkl\u00e4rung: <a href=\"https:\/\/updraftplus.com\/data-protection-and-privacy-centre\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/updraftplus.com\/data-protection-and-privacy-centre\/<\/a>.<\/li>\n<li><strong>Wordfence:<\/strong> Firewall und Sicherheits- sowie Fehlererkennungsfunktionen; Dienstanbieter: Defiant, Inc., 800 5th Ave Ste 4100, Seattle, WA 98104, USA; Website: <a href=\"https:\/\/www.wordfence.com\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.wordfence.com<\/a>; Datenschutzerkl\u00e4rung: <a href=\"https:\/\/www.wordfence.com\/privacy-policy\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.wordfence.com\/privacy-policy\/<\/a>; Standardvertragsklauseln (Gew\u00e4hrleistung Datenschutzniveau bei Verarbeitung in Drittl\u00e4ndern): <a href=\"https:\/\/www.wordfence.com\/gdpr\/dpa.pdf\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.wordfence.com\/gdpr\/dpa.pdf<\/a>.<\/li>\n<\/ul>\n<h2 id=\"m29\">Cloud-Dienste<\/h2>\n<p>Wir nutzen \u00fcber das Internet zug\u00e4ngliche und auf den Servern ihrer Anbieter ausgef\u00fchrte Softwaredienste (sogenannte \u201eCloud-Dienste\u201c, auch bezeichnet als \u201eSoftware as a Service\u201c) f\u00fcr die folgenden Zwecke: Dokumentenspeicherung und Verwaltung, Kalenderverwaltung, E-Mail-Versand, Tabellenkalkulationen und Pr\u00e4sentationen, Austausch von Dokumenten, Inhalten und Informationen mit bestimmten Empf\u00e4ngern oder Ver\u00f6ffentlichung von Webseiten, Formularen oder sonstigen Inhalten und Informationen sowie Chats und Teilnahme an Audio- und Videokonferenzen.<\/p>\n<p>In diesem Rahmen k\u00f6nnen personenbezogenen Daten verarbeitet und auf den Servern der Anbieter gespeichert werden, soweit diese Bestandteil von Kommunikationsvorg\u00e4ngen mit uns sind oder von uns sonst, wie im Rahmen dieser Datenschutzerkl\u00e4rung dargelegt, verarbeitet werden. Zu diesen Daten k\u00f6nnen insbesondere Stammdaten und Kontaktdaten der Nutzer, Daten zu Vorg\u00e4ngen, Vertr\u00e4gen, sonstigen Prozessen und deren Inhalte geh\u00f6ren. Die Anbieter der Cloud-Dienste verarbeiten ferner Nutzungsdaten und Metadaten, die von ihnen zu Sicherheitszwecken und zur Serviceoptimierung verwendet werden.<\/p>\n<p>Sofern wir mit Hilfe der Cloud-Dienste f\u00fcr andere Nutzer oder \u00f6ffentlich zug\u00e4ngliche Webseiten Formulare o.a. Dokumente und Inhalte bereitstellen, k\u00f6nnen die Anbieter Cookies auf den Ger\u00e4ten der Nutzer f\u00fcr Zwecke der Webanalyse oder, um sich Einstellungen der Nutzer (z.B. im Fall der Mediensteuerung) zu merken, speichern.<\/p>\n<p><strong>Hinweise zu Rechtsgrundlagen:<\/strong> Sofern wir um eine Einwilligung in den Einsatz der Cloud-Dienste bitten, ist die Rechtsgrundlage der Verarbeitung die Einwilligung. Ferner kann deren Einsatz ein Bestandteil unserer (vor)vertraglichen Leistungen sein, sofern der Einsatz der Cloud-Dienste in diesem Rahmen vereinbart wurde. Ansonsten werden die Daten der Nutzer auf Grundlage unserer berechtigten Interessen (d.h., Interesse an effizienten und sicheren Verwaltungs- und Kollaborationsprozessen) verarbeitet<\/p>\n<ul>\n<li><strong>Verarbeitete Datenarten:<\/strong> Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail, Telefonnummern), Inhaltsdaten (z.B. Eingaben in Onlineformularen), Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen).<\/li>\n<li><strong>Betroffene Personen:<\/strong> Kunden, Besch\u00e4ftigte (z.B. Angestellte, Bewerber, ehemalige Mitarbeiter), Interessenten, Kommunikationspartner.<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> B\u00fcro- und Organisationsverfahren.<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Einwilligung (Art. 6 Abs. 1 S. 1 lit. a. DSGVO), Vertragserf\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO).<\/li>\n<\/ul>\n<p><strong>Eingesetzte Dienste und Diensteanbieter:<\/strong><\/p>\n<ul>\n<li><strong>Microsoft Clouddienste:<\/strong> Cloud-Speicher-Dienste; Dienstanbieter: Microsoft Corporation, One Microsoft Way, Redmond, WA 98052-6399 USA; Website: <a href=\"https:\/\/microsoft.com\/de-de\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/microsoft.com\/de-de<\/a>; Datenschutzerkl\u00e4rung: <a href=\"https:\/\/privacy.microsoft.com\/de-de\/privacystatement\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/privacy.microsoft.com\/de-de\/privacystatement<\/a>, Sicherheitshinweise: <a href=\"https:\/\/www.microsoft.com\/de-de\/trustcenter\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.microsoft.com\/de-de\/trustcenter<\/a>.<\/li>\n<\/ul>\n<h2 id=\"m17\">Newsletter und elektronische Benachrichtigungen<\/h2>\n<p>Wir versenden Newsletter, E-Mails und weitere elektronische Benachrichtigungen (nachfolgend \u201eNewsletter\u201c) nur mit der Einwilligung der Empf\u00e4nger oder einer gesetzlichen Erlaubnis. Sofern im Rahmen einer Anmeldung zum Newsletter dessen Inhalte konkret umschrieben werden, sind sie f\u00fcr die Einwilligung der Nutzer ma\u00dfgeblich. Im \u00dcbrigen enthalten unsere Newsletter Informationen zu unseren Leistungen und uns.<\/p>\n<p>Um sich zu unseren Newslettern anzumelden, reicht es grunds\u00e4tzlich aus, wenn Sie Ihre E-Mail-Adresse angeben. Wir k\u00f6nnen Sie jedoch bitten, einen Namen, zwecks pers\u00f6nlicher Ansprache im Newsletter, oder weitere Angaben, sofern diese f\u00fcr die Zwecke des Newsletters erforderlich sind, zu t\u00e4tigen.<\/p>\n<p><strong>Double-Opt-In-Verfahren:<\/strong> Die Anmeldung zu unserem Newsletter erfolgt grunds\u00e4tzlich in einem sogenannte Double-Opt-In-Verfahren. D.h., Sie erhalten nach der Anmeldung eine E-Mail, in der Sie um die Best\u00e4tigung Ihrer Anmeldung gebeten werden. Diese Best\u00e4tigung ist notwendig, damit sich niemand mit fremden E-Mail-Adressen anmelden kann. Die Anmeldungen zum Newsletter werden protokolliert, um den Anmeldeprozess entsprechend den rechtlichen Anforderungen nachweisen zu k\u00f6nnen. Hierzu geh\u00f6rt die Speicherung des Anmelde- und des Best\u00e4tigungszeitpunkts als auch der IP-Adresse. Ebenso werden die \u00c4nderungen Ihrer bei dem Versanddienstleister gespeicherten Daten protokolliert.<\/p>\n<p><strong>L\u00f6schung und Einschr\u00e4nkung der Verarbeitung:<\/strong> Wir k\u00f6nnen die ausgetragenen E-Mail-Adressen bis zu drei Jahren auf Grundlage unserer berechtigten Interessen speichern, bevor wir sie l\u00f6schen, um eine ehemals gegebene Einwilligung nachweisen zu k\u00f6nnen. Die Verarbeitung dieser Daten wird auf den Zweck einer m\u00f6glichen Abwehr von Anspr\u00fcchen beschr\u00e4nkt. Ein individueller L\u00f6schungsantrag ist jederzeit m\u00f6glich, sofern zugleich das ehemalige Bestehen einer Einwilligung best\u00e4tigt wird. Im Fall von Pflichten zur dauerhaften Beachtung von Widerspr\u00fcchen behalten wir uns die Speicherung der E-Mail-Adresse alleine zu diesem Zweck in einer Sperrliste (sogenannte \u201eBlocklist\u201c) vor.<\/p>\n<p>Die Protokollierung des Anmeldeverfahrens erfolgt auf Grundlage unserer berechtigten Interessen zu Zwecken des Nachweises seines ordnungsgem\u00e4\u00dfen Ablaufs. Soweit wir einen Dienstleister mit dem Versand von E-Mails beauftragen, erfolgt dies auf Grundlage unserer berechtigten Interessen an einem effizienten und sicheren Versandsystem.<\/p>\n<p><strong>Hinweise zu Rechtsgrundlagen:<\/strong> Der Versand der Newsletter erfolgt auf Grundlage einer Einwilligung der Empf\u00e4nger oder, falls eine Einwilligung nicht erforderlich ist, auf Grundlage unserer berechtigten Interessen am Direktmarketing, sofern und soweit diese gesetzlich, z.B. im Fall von Bestandskundenwerbung, erlaubt ist. Soweit wir einen Dienstleister mit dem Versand von E-Mails beauftragen, geschieht dies auf der Grundlage unserer berechtigten Interessen. Das Registrierungsverfahren wird auf der Grundlage unserer berechtigten Interessen aufgezeichnet, um nachzuweisen, dass es in \u00dcbereinstimmung mit dem Gesetz durchgef\u00fchrt wurde.<\/p>\n<p>Inhalte: Informationen zu unserem Angebot an Antiquit\u00e4ten, Veranstaltungen und Fachinformationen zu den Objekten.<\/p>\n<p><strong>Messung von \u00d6ffnungs- und Klickraten<\/strong>: Die Newsletter enthalten einen sogenannte \u201eweb-beacon\u201c, d.h., eine pixelgro\u00dfe Datei, die beim \u00d6ffnen des Newsletters von unserem Server, bzw., sofern wir einen Versanddienstleister einsetzen, von dessen Server abgerufen wird. Im Rahmen dieses Abrufs werden zun\u00e4chst technische Informationen, wie Informationen zum Browser und Ihrem System, als auch Ihre IP-Adresse und der Zeitpunkt des Abrufs, erhoben.<\/p>\n<p>Diese Informationen werden zur technischen Verbesserung unseres Newsletters anhand der technischen Daten oder der Zielgruppen und ihres Leseverhaltens auf Basis ihrer Abruforte (die mit Hilfe der IP-Adresse bestimmbar sind) oder der Zugriffszeiten genutzt. Diese Analyse beinhaltet ebenfalls die Feststellung, ob die Newsletter ge\u00f6ffnet werden, wann sie ge\u00f6ffnet werden und welche Links geklickt werden. Diese Informationen werden den einzelnen Newsletterempf\u00e4ngern zugeordnet und in deren Profilen bis zu deren L\u00f6schung gespeichert. Die Auswertungen dienen uns dazu, die Lesegewohnheiten unserer Nutzer zu erkennen und unsere Inhalte an sie anzupassen oder unterschiedliche Inhalte entsprechend den Interessen unserer Nutzer zu versenden.<\/p>\n<p>Die Messung der \u00d6ffnungsraten und der Klickraten sowie Speicherung der Messergebnisse in den Profilen der Nutzer sowie deren weitere Verarbeitung erfolgen auf Grundlage einer Einwilligung der Nutzer.<\/p>\n<p>Ein getrennter Widerruf der Erfolgsmessung ist leider nicht m\u00f6glich, in diesem Fall muss das gesamte Newsletterabonnement gek\u00fcndigt, bzw. muss ihm widersprochen werden. In diesem Fall werden die gespeicherten Profilinformationen gel\u00f6scht.<\/p>\n<ul>\n<li><strong>Verarbeitete Datenarten:<\/strong> Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail, Telefonnummern), Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen), Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten).<\/li>\n<li><strong>Betroffene Personen:<\/strong> Kommunikationspartner.<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> Direktmarketing (z.B. per E-Mail oder postalisch).<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Einwilligung (Art. 6 Abs. 1 S. 1 lit. a. DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO).<\/li>\n<li><strong>Widerspruchsm\u00f6glichkeit (Opt-Out):<\/strong> Sie k\u00f6nnen den Empfang unseres Newsletters jederzeit k\u00fcndigen, d.h. Ihre Einwilligungen widerrufen, bzw. dem weiteren Empfang widersprechen. Einen Link zur K\u00fcndigung des Newsletters finden Sie entweder am Ende eines jeden Newsletters oder k\u00f6nnen sonst eine der oben angegebenen Kontaktm\u00f6glichkeiten, vorzugsw\u00fcrdig E-Mail, hierzu nutzen.<\/li>\n<\/ul>\n<p><strong>Eingesetzte Dienste und Diensteanbieter:<\/strong><\/p>\n<ul>\n<li><strong>CleverReach:<\/strong> E-Mail-Marketing-Plattform; Dienstanbieter: CleverReach GmbH &amp; Co. KG, \/\/CRASH Building, Schafj\u00fcckenweg 2, 26180 Rastede, Deutschland; Website: <a href=\"https:\/\/www.cleverreach.com\/de\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.cleverreach.com\/de<\/a>; Datenschutzerkl\u00e4rung: <a href=\"https:\/\/www.cleverreach.com\/de\/datenschutz\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.cleverreach.com\/de\/datenschutz\/<\/a>.<\/li>\n<\/ul>\n<h2 id=\"m263\">Webanalyse, Monitoring und Optimierung<\/h2>\n<p>Die Webanalyse (auch als \u201eReichweitenmessung\u201c bezeichnet) dient der Auswertung der Besucherstr\u00f6me unseres Onlineangebotes und kann Verhalten, Interessen oder demographische Informationen zu den Besuchern, wie z.B. das Alter oder das Geschlecht, als pseudonyme Werte umfassen. Mit Hilfe der Reichweitenanalyse k\u00f6nnen wir z.B. erkennen, zu welcher Zeit unser Onlineangebot oder dessen Funktionen oder Inhalte am h\u00e4ufigsten genutzt werden oder zur Wiederverwendung einladen. Ebenso k\u00f6nnen wir nachvollziehen, welche Bereiche der Optimierung bed\u00fcrfen.<\/p>\n<p>Neben der Webanalyse k\u00f6nnen wir auch Testverfahren einsetzen, um z.B. unterschiedliche Versionen unseres Onlineangebotes oder seiner Bestandteile zu testen und optimieren.<\/p>\n<p>Zu diesen Zwecken k\u00f6nnen sogenannte Nutzerprofile angelegt und in einer Datei (sogenannte \u201eCookie\u201c) gespeichert oder \u00e4hnliche Verfahren mit dem gleichen Zweck genutzt werden. Zu diesen Angaben k\u00f6nnen z.B. betrachtete Inhalte, besuchte Webseiten und dort genutzte Elemente und technische Angaben, wie der verwendete Browser, das verwendete Computersystem sowie Angaben zu Nutzungszeiten geh\u00f6ren. Sofern Nutzer in die Erhebung ihrer Standortdaten eingewilligt haben, k\u00f6nnen je nach Anbieter auch diese verarbeitet werden.<\/p>\n<p>Es werden ebenfalls die IP-Adressen der Nutzer gespeichert. Jedoch nutzen wir ein IP-Masking-Verfahren (d.h., Pseudonymisierung durch K\u00fcrzung der IP-Adresse) zum Schutz der Nutzer. Generell werden die im Rahmen von Webanalyse, A\/B-Testings und Optimierung keine Klardaten der Nutzer (wie z.B. E-Mail-Adressen oder Namen) gespeichert, sondern Pseudonyme. D.h., wir als auch die Anbieter der eingesetzten Software kennen nicht die tats\u00e4chliche Identit\u00e4t der Nutzer, sondern nur den f\u00fcr Zwecke der jeweiligen Verfahren in deren Profilen gespeicherten Angaben.<\/p>\n<p><strong>Hinweise zu Rechtsgrundlagen:<\/strong> Sofern wir die Nutzer um deren Einwilligung in den Einsatz der Drittanbieter bitten, ist die Rechtsgrundlage der Verarbeitung von Daten die Einwilligung. Ansonsten werden die Daten der Nutzer auf Grundlage unserer berechtigten Interessen (d.h. Interesse an effizienten, wirtschaftlichen und empf\u00e4ngerfreundlichen Leistungen) verarbeitet. In diesem Zusammenhang m\u00f6chten wir Sie auch auf die Informationen zur Verwendung von Cookies in dieser Datenschutzerkl\u00e4rung hinweisen.<\/p>\n<ul>\n<li><strong>Verarbeitete Datenarten:<\/strong> Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen).<\/li>\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> Reichweitenmessung (z.B. Zugriffsstatistiken, Erkennung wiederkehrender Besucher), Profile mit nutzerbezogenen Informationen (Erstellen von Nutzerprofilen).<\/li>\n<li><strong>Sicherheitsma\u00dfnahmen:<\/strong> IP-Masking (Pseudonymisierung der IP-Adresse).<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Einwilligung (Art. 6 Abs. 1 S. 1 lit. a. DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO).<\/li>\n<\/ul>\n<p><strong>Eingesetzte Dienste und Diensteanbieter:<\/strong><\/p>\n<ul>\n<li><strong>Google Analytics:<\/strong> Reichweitenmessung und Webanalyse; Dienstanbieter: Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irland, Mutterunternehmen: Google LLC, 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA; Website: <a href=\"https:\/\/marketingplatform.google.com\/intl\/de\/about\/analytics\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/marketingplatform.google.com\/intl\/de\/about\/analytics\/<\/a>; Datenschutzerkl\u00e4rung: <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/policies.google.com\/privacy<\/a>.<\/li>\n<\/ul>\n<h2 id=\"m136\">Pr\u00e4senzen in sozialen Netzwerken (Social Media)<\/h2>\n<p>Wir unterhalten Onlinepr\u00e4senzen innerhalb sozialer Netzwerke und verarbeiten in diesem Rahmen Daten der Nutzer, um mit den dort aktiven Nutzern zu kommunizieren oder um Informationen \u00fcber uns anzubieten.<\/p>\n<p>Wir weisen darauf hin, dass dabei Daten der Nutzer au\u00dferhalb des Raumes der Europ\u00e4ischen Union verarbeitet werden k\u00f6nnen. Hierdurch k\u00f6nnen sich f\u00fcr die Nutzer Risiken ergeben, weil so z.B. die Durchsetzung der Rechte der Nutzer erschwert werden k\u00f6nnte.<\/p>\n<p>Ferner werden die Daten der Nutzer innerhalb sozialer Netzwerke im Regelfall f\u00fcr Marktforschungs- und Werbezwecke verarbeitet. So k\u00f6nnen z.B. anhand des Nutzungsverhaltens und sich daraus ergebender Interessen der Nutzer Nutzungsprofile erstellt werden. Die Nutzungsprofile k\u00f6nnen wiederum verwendet werden, um z.B. Werbeanzeigen innerhalb und au\u00dferhalb der Netzwerke zu schalten, die mutma\u00dflich den Interessen der Nutzer entsprechen. Zu diesen Zwecken werden im Regelfall Cookies auf den Rechnern der Nutzer gespeichert, in denen das Nutzungsverhalten und die Interessen der Nutzer gespeichert werden. Ferner k\u00f6nnen in den Nutzungsprofilen auch Daten unabh\u00e4ngig der von den Nutzern verwendeten Ger\u00e4te gespeichert werden (insbesondere, wenn die Nutzer Mitglieder der jeweiligen Plattformen sind und bei diesen eingeloggt sind).<\/p>\n<p>F\u00fcr eine detaillierte Darstellung der jeweiligen Verarbeitungsformen und der Widerspruchsm\u00f6glichkeiten (Opt-Out) verweisen wir auf die Datenschutzerkl\u00e4rungen und Angaben der Betreiber der jeweiligen Netzwerke.<\/p>\n<p>Auch im Fall von Auskunftsanfragen und der Geltendmachung von Betroffenenrechten weisen wir darauf hin, dass diese am effektivsten bei den Anbietern geltend gemacht werden k\u00f6nnen. Nur die Anbieter haben jeweils Zugriff auf die Daten der Nutzer und k\u00f6nnen direkt entsprechende Ma\u00dfnahmen ergreifen und Ausk\u00fcnfte geben. Sollten Sie dennoch Hilfe ben\u00f6tigen, dann k\u00f6nnen Sie sich an uns wenden.<\/p>\n<p><strong>Facebook<\/strong>: Wir sind gemeinsam mit Facebook Irland Ltd. f\u00fcr die Erhebung (jedoch nicht die weitere Verarbeitung) von Daten der Besucher unserer Facebook-Seite (sog. \u201eFanpage\u201c) verantwortlich. Zu diesen Daten geh\u00f6ren Informationen zu den Arten von Inhalten, die Nutzer sich ansehen oder mit denen sie interagieren, oder die von ihnen vorgenommenen Handlungen (siehe unter \u201eVon dir und anderen get\u00e4tigte und bereitgestellte Dinge\u201c in der Facebook-Datenrichtlinie: <a href=\"https:\/\/www.facebook.com\/policy\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.facebook.com\/policy<\/a>), sowie Informationen \u00fcber die von den Nutzern genutzten Ger\u00e4te (z. B. IP-Adressen, Betriebssystem, Browsertyp, Spracheinstellungen, Cookie-Daten; siehe unter \u201eGer\u00e4teinformationen\u201c in der Facebook-Datenrichtlinie-erkl\u00e4rung: <a href=\"https:\/\/www.facebook.com\/policy\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.facebook.com\/policy<\/a>). Wie in der Facebook-Datenrichtlinie unter \u201eWie verwenden wir diese Informationen?\u201c erl\u00e4utert, erhebt und verwendet Facebook Informationen auch, um Analysedienste, so genannte \u201eSeiten-Insights\u201c, f\u00fcr Seitenbetreiber bereitzustellen, damit diese Erkenntnisse dar\u00fcber erhalten, wie Personen mit ihren Seiten und mit den mit ihnen verbundenen Inhalten interagieren. Wir haben mit Facebook eine spezielle Vereinbarung abgeschlossen (\u201eInformationen zu Seiten-Insights\u201c, <a href=\"https:\/\/www.facebook.com\/legal\/terms\/page_controller_addendum\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.facebook.com\/legal\/terms\/page_controller_addendum<\/a>), in der insbesondere geregelt wird, welche Sicherheitsma\u00dfnahmen Facebook beachten muss und in der Facebook sich bereit erkl\u00e4rt hat die Betroffenenrechte zu erf\u00fcllen (d. h. Nutzer k\u00f6nnen z. B. Ausk\u00fcnfte oder L\u00f6schungsanfragen direkt an Facebook richten). Die Rechte der Nutzer (insbesondere auf Auskunft, L\u00f6schung, Widerspruch und Beschwerde bei zust\u00e4ndiger Aufsichtsbeh\u00f6rde), werden durch die Vereinbarungen mit Facebook nicht eingeschr\u00e4nkt. Weitere Hinweise finden sich in den \u201eInformationen zu Seiten-Insights\u201c (<a href=\"https:\/\/www.facebook.com\/legal\/terms\/information_about_page_insights_data\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.facebook.com\/legal\/terms\/information_about_page_insights_data<\/a>).<\/p>\n<ul>\n<li><strong>Verarbeitete Datenarten:<\/strong> Kontaktdaten (z.B. E-Mail, Telefonnummern), Inhaltsdaten (z.B. Eingaben in Onlineformularen), Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen).<\/li>\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> Kontaktanfragen und Kommunikation, Feedback (z.B. Sammeln von Feedback via Online-Formular), Marketing.<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO).<\/li>\n<\/ul>\n<p><strong>Eingesetzte Dienste und Diensteanbieter:<\/strong><\/p>\n<ul>\n<li><strong>Instagram:<\/strong> Soziales Netzwerk; Dienstanbieter: Instagram Inc., 1601 Willow Road, Menlo Park, CA, 94025, USA, Mutterunternehmen: Facebook, 1 Hacker Way, Menlo Park, CA 94025, USA; Website: <a href=\"https:\/\/www.instagram.com\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.instagram.com<\/a>; Datenschutzerkl\u00e4rung: <a href=\"https:\/\/instagram.com\/about\/legal\/privacy\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/instagram.com\/about\/legal\/privacy<\/a>.<\/li>\n<li><strong>Facebook:<\/strong> Soziales Netzwerk; Dienstanbieter: Facebook Ireland Ltd., 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irland, Mutterunternehmen: Facebook, 1 Hacker Way, Menlo Park, CA 94025, USA; Website: <a href=\"https:\/\/www.facebook.com\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.facebook.com<\/a>; Datenschutzerkl\u00e4rung: <a href=\"https:\/\/www.facebook.com\/about\/privacy\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.facebook.com\/about\/privacy<\/a>; Widerspruchsm\u00f6glichkeit (Opt-Out): Einstellungen f\u00fcr Werbeanzeigen: <a href=\"https:\/\/www.facebook.com\/adpreferences\/ad_settings\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.facebook.com\/adpreferences\/ad_settings<\/a>.<\/li>\n<\/ul>\n<h2 id=\"m328\">Plugins und eingebettete Funktionen sowie Inhalte<\/h2>\n<p>Wir binden in unser Onlineangebot Funktions- und Inhaltselemente ein, die von den Servern ihrer jeweiligen Anbieter (nachfolgend bezeichnet als \u201eDrittanbieter\u201d) bezogen werden. Dabei kann es sich zum Beispiel um Grafiken, Videos oder Stadtpl\u00e4ne handeln (nachfolgend einheitlich bezeichnet als \u201eInhalte\u201d).<\/p>\n<p>Die Einbindung setzt immer voraus, dass die Drittanbieter dieser Inhalte die IP-Adresse der Nutzer verarbeiten, da sie ohne die IP-Adresse die Inhalte nicht an deren Browser senden k\u00f6nnten. Die IP-Adresse ist damit f\u00fcr die Darstellung dieser Inhalte oder Funktionen erforderlich. Wir bem\u00fchen uns, nur solche Inhalte zu verwenden, deren jeweilige Anbieter die IP-Adresse lediglich zur Auslieferung der Inhalte verwenden. Drittanbieter k\u00f6nnen ferner sogenannte Pixel-Tags (unsichtbare Grafiken, auch als \u201eWeb Beacons\u201c bezeichnet) f\u00fcr statistische oder Marketingzwecke verwenden. Durch die \u201ePixel-Tags\u201c k\u00f6nnen Informationen, wie der Besucherverkehr auf den Seiten dieser Webseite, ausgewertet werden. Die pseudonymen Informationen k\u00f6nnen ferner in Cookies auf dem Ger\u00e4t der Nutzer gespeichert werden und unter anderem technische Informationen zum Browser und zum Betriebssystem, zu verweisenden Webseiten, zur Besuchszeit sowie weitere Angaben zur Nutzung unseres Onlineangebotes enthalten als auch mit solchen Informationen aus anderen Quellen verbunden werden.<\/p>\n<p><strong>Hinweise zu Rechtsgrundlagen:<\/strong> Sofern wir die Nutzer um deren Einwilligung in den Einsatz der Drittanbieter bitten, ist die Rechtsgrundlage der Verarbeitung von Daten die Einwilligung. Ansonsten werden die Daten der Nutzer auf Grundlage unserer berechtigten Interessen (d.h. Interesse an effizienten, wirtschaftlichen und empf\u00e4ngerfreundlichen Leistungen) verarbeitet. In diesem Zusammenhang m\u00f6chten wir Sie auch auf die Informationen zur Verwendung von Cookies in dieser Datenschutzerkl\u00e4rung hinweisen.<\/p>\n<p><strong>Facebook-Plugins und -Inhalte<\/strong>: Wir sind gemeinsam mit Facebook Irland Ltd. f\u00fcr die Erhebung oder den Erhalt im Rahmen einer \u00dcbermittlung (jedoch nicht die weitere Verarbeitung) von \u201eEvent-Daten\u201c, die Facebook mittels der Facebook-Social-Plugins (und Einbettungsfunktionen f\u00fcr Inhalte), die auf unserem Onlineangebot ausgef\u00fchrt werden, erhebt oder im Rahmen einer \u00dcbermittlung zu folgenden Zwecken erh\u00e4lt, gemeinsam verantwortlich: a) Anzeige von Inhalten sowie Werbeinformationen, die den mutma\u00dflichen Interessen der Nutzer entsprechen; b) Zustellung kommerzieller und transaktionsbezogener Nachrichten (z. B. Ansprache von Nutzern via Facebook-Messenger); c) Verbesserung der Anzeigenauslieferung und Personalisierung von Funktionen und Inhalten (z. B. Verbesserung der Erkennung, welche Inhalte oder Werbeinformationen mutma\u00dflich den Interessen der Nutzer entsprechen). Wir haben mit Facebook eine spezielle Vereinbarung abgeschlossen (\u201eZusatz f\u00fcr Verantwortliche\u201c, <a href=\"https:\/\/www.facebook.com\/legal\/controller_addendum\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.facebook.com\/legal\/controller_addendum<\/a>), in der insbesondere geregelt wird, welche Sicherheitsma\u00dfnahmen Facebook beachten muss (<a href=\"https:\/\/www.facebook.com\/legal\/terms\/data_security_terms\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.facebook.com\/legal\/terms\/data_security_terms<\/a>) und in der Facebook sich bereit erkl\u00e4rt hat die Betroffenenrechte zu erf\u00fcllen (d. h. Nutzer k\u00f6nnen z. B. Ausk\u00fcnfte oder L\u00f6schungsanfragen direkt an Facebook richten). Hinweis: Wenn Facebook uns Messwerte, Analysen und Berichte bereitstellt (die aggregiert sind, d. h. keine Angaben zu einzelnen Nutzern erhalten und f\u00fcr uns anonym sind), dann erfolgt diese Verarbeitung nicht im Rahmen der gemeinsamen Verantwortlichkeit, sondern auf Grundlage eines Auftragsverarbeitungsvertrages (\u201eDatenverarbeitungsbedingungen \u201e, <a href=\"https:\/\/www.facebook.com\/legal\/terms\/dataprocessing\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.facebook.com\/legal\/terms\/dataprocessing<\/a>) , der \u201eDatensicherheitsbedingungen\u201c (<a href=\"https:\/\/www.facebook.com\/legal\/terms\/data_security_terms\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.facebook.com\/legal\/terms\/data_security_terms<\/a>) sowie im Hinblick auf die Verarbeitung in den USA auf Grundlage von Standardvertragsklauseln (\u201eFacebook-EU-Daten\u00fcbermittlungszusatz, <a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum<\/a>). Die Rechte der Nutzer (insbesondere auf Auskunft, L\u00f6schung, Widerspruch und Beschwerde bei zust\u00e4ndiger Aufsichtsbeh\u00f6rde), werden durch die Vereinbarungen mit Facebook nicht eingeschr\u00e4nkt.<\/p>\n<p><strong>Instagram-Plugins und -Inhalte<\/strong>: Wir sind gemeinsam mit Facebook Irland Ltd. f\u00fcr die Erhebung oder den Erhalt im Rahmen einer \u00dcbermittlung (jedoch nicht die weitere Verarbeitung) von \u201eEvent-Daten\u201c, die Facebook mittels Funktionen von Instagram (z. B. Einbettungsfunktionen f\u00fcr Inhalte), die auf unserem Onlineangebot ausgef\u00fchrt werden, erhebt oder im Rahmen einer \u00dcbermittlung zu folgenden Zwecken erh\u00e4lt, gemeinsam verantwortlich: a) Anzeige von Inhalten sowie Werbeinformationen, die den mutma\u00dflichen Interessen der Nutzer entsprechen; b) Zustellung kommerzieller und transaktionsbezogener Nachrichten (z. B. Ansprache von Nutzern via Facebook-Messenger); c) Verbesserung der Anzeigenauslieferung und Personalisierung von Funktionen und Inhalten (z. B. Verbesserung der Erkennung, welche Inhalte oder Werbeinformationen mutma\u00dflich den Interessen der Nutzer entsprechen). Wir haben mit Facebook eine spezielle Vereinbarung abgeschlossen (\u201eZusatz f\u00fcr Verantwortliche\u201c, <a href=\"https:\/\/www.facebook.com\/legal\/controller_addendum\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.facebook.com\/legal\/controller_addendum<\/a>), in der insbesondere geregelt wird, welche Sicherheitsma\u00dfnahmen Facebook beachten muss (<a href=\"https:\/\/www.facebook.com\/legal\/terms\/data_security_terms\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.facebook.com\/legal\/terms\/data_security_terms<\/a>) und in der Facebook sich bereit erkl\u00e4rt hat die Betroffenenrechte zu erf\u00fcllen (d. h. Nutzer k\u00f6nnen z. B. Ausk\u00fcnfte oder L\u00f6schungsanfragen direkt an Facebook richten). Hinweis: Wenn Facebook uns Messwerte, Analysen und Berichte bereitstellt (die aggregiert sind, d. h. keine Angaben zu einzelnen Nutzern erhalten und f\u00fcr uns anonym sind), dann erfolgt diese Verarbeitung nicht im Rahmen der gemeinsamen Verantwortlichkeit, sondern auf Grundlage eines Auftragsverarbeitungsvertrages (\u201eDatenverarbeitungsbedingungen \u201e, <a href=\"https:\/\/www.facebook.com\/legal\/terms\/dataprocessing\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.facebook.com\/legal\/terms\/dataprocessing<\/a>) , der \u201eDatensicherheitsbedingungen\u201c (<a href=\"https:\/\/www.facebook.com\/legal\/terms\/data_security_terms\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.facebook.com\/legal\/terms\/data_security_terms<\/a>) sowie im Hinblick auf die Verarbeitung in den USA auf Grundlage von Standardvertragsklauseln (\u201eFacebook-EU-Daten\u00fcbermittlungszusatz, <a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum<\/a>). Die Rechte der Nutzer (insbesondere auf Auskunft, L\u00f6schung, Widerspruch und Beschwerde bei zust\u00e4ndiger Aufsichtsbeh\u00f6rde), werden durch die Vereinbarungen mit Facebook nicht eingeschr\u00e4nkt.<\/p>\n<ul>\n<li><strong>Verarbeitete Datenarten:<\/strong> Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\/Kommunikationsdaten (z.B. Ger\u00e4te-Informationen, IP-Adressen), Event-Daten (Facebook) (\u201eEvent-Daten\u201c sind Daten, die z. B. via Facebook-Pixel (via Apps oder auf anderen Wegen) von uns an Facebook \u00fcbermittelt werden k\u00f6nnen und sich auf Personen oder deren Handlungen beziehen; Zu den Daten geh\u00f6ren z. B. Angaben \u00fcber Besuche auf Websites, Interaktionen mit Inhalten, Funktionen, Installationen von Apps, K\u00e4ufe von Produkten, etc.; die Event-Daten werden zwecks Bildung von Zielgruppen f\u00fcr Inhalte und Werbeinformationen (Custom Audiences) verarbeitet; Event Daten beinhalten nicht die eigentlichen Inhalte (wie z. B. verfasste Kommentare), keine Login-Informationen und keine Kontaktinformationen (also keine Namen, E-Mail-Adressen und Telefonnummern). Event Daten werden durch Facebook nach maximal zwei Jahren gel\u00f6scht, die aus ihnen gebildeten Zielgruppen mit der L\u00f6schung unseres Facebook-Kontos), Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail, Telefonnummern), Inhaltsdaten (z.B. Eingaben in Onlineformularen).<\/li>\n<li><strong>Betroffene Personen:<\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\/li>\n<li><strong>Zwecke der Verarbeitung:<\/strong> Bereitstellung unseres Onlineangebotes und Nutzerfreundlichkeit, Erbringung vertragliche Leistungen und Kundenservice, Marketing, Profile mit nutzerbezogenen Informationen (Erstellen von Nutzerprofilen).<\/li>\n<li><strong>Rechtsgrundlagen:<\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO), Einwilligung (Art. 6 Abs. 1 S. 1 lit. a. DSGVO), Vertragserf\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO).<\/li>\n<\/ul>\n<p><strong>Eingesetzte Dienste und Diensteanbieter:<\/strong><\/p>\n<ul>\n<li><strong>Facebook-Plugins und -Inhalte:<\/strong> Facebook Social Plugins und Inhalte \u2013 Hierzu k\u00f6nnen z.B. Inhalte wie Bilder, Videos oder Texte und Schaltfl\u00e4chen geh\u00f6ren, mit denen Nutzer Inhalte dieses Onlineangebotes innerhalb von Facebook teilen k\u00f6nnen. Die Liste und das Aussehen der Facebook Social Plugins k\u00f6nnen hier eingesehen werden: <a href=\"https:\/\/developers.facebook.com\/docs\/plugins\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/developers.facebook.com\/docs\/plugins\/<\/a>; Dienstanbieter: Facebook Ireland Ltd., 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irland, Mutterunternehmen: Facebook, 1 Hacker Way, Menlo Park, CA 94025, USA; Website: <a href=\"https:\/\/www.facebook.com\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.facebook.com<\/a>; Datenschutzerkl\u00e4rung: <a href=\"https:\/\/www.facebook.com\/about\/privacy\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.facebook.com\/about\/privacy<\/a>; Widerspruchsm\u00f6glichkeit (Opt-Out): Einstellungen f\u00fcr Werbeanzeigen: <a href=\"https:\/\/www.facebook.com\/adpreferences\/ad_settings\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.facebook.com\/adpreferences\/ad_settings<\/a>.<\/li>\n<li><strong>Instagram-Plugins und -Inhalte:<\/strong> Instagram Plugins und -Inhalte \u2013 Hierzu k\u00f6nnen z.B. Inhalte wie Bilder, Videos oder Texte und Schaltfl\u00e4chen geh\u00f6ren, mit denen Nutzer Inhalte dieses Onlineangebotes innerhalb von Instagram teilen k\u00f6nnen. Dienstanbieter: <a href=\"https:\/\/www.instagram.com\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.instagram.com<\/a>, Instagram Inc., 1601 Willow Road, Menlo Park, CA, 94025, USA; Website: <a href=\"https:\/\/www.instagram.com\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.instagram.com<\/a>; Datenschutzerkl\u00e4rung: <a href=\"https:\/\/instagram.com\/about\/legal\/privacy\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/instagram.com\/about\/legal\/privacy<\/a>.<\/li>\n<li><strong>Soundcloud Music Player Widget:<\/strong> Soundcloud Music Player Widget; Dienstanbieter: SoundCloud Limited, Rheinsberger Str. 76\/77, 10115 Berlin, Deutschland; Website: <a href=\"https:\/\/soundcloud.com\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/soundcloud.com<\/a>; Datenschutzerkl\u00e4rung: <a href=\"https:\/\/soundcloud.com\/pages\/privacy\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/soundcloud.com\/pages\/privacy<\/a>.<\/li>\n<li><strong>YouTube-Videos:<\/strong> Videoinhalte; Dienstanbieter: Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irland, Mutterunternehmen: Google LLC, 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA; Website: <a href=\"https:\/\/www.youtube.com\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/www.youtube.com<\/a>; Datenschutzerkl\u00e4rung: <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/policies.google.com\/privacy<\/a>; Widerspruchsm\u00f6glichkeit (Opt-Out): Opt-Out-Plugin: <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/a>, Einstellungen f\u00fcr die Darstellung von Werbeeinblendungen: <a href=\"https:\/\/adssettings.google.com\/authenticated\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\">https:\/\/adssettings.google.com\/authenticated<\/a>.<\/li>\n<\/ul>\n<h2 id=\"m12\">L\u00f6schung von Daten<\/h2>\n<p>Die von uns verarbeiteten Daten werden nach Ma\u00dfgabe der gesetzlichen Vorgaben gel\u00f6scht, sobald deren zur Verarbeitung erlaubten Einwilligungen widerrufen werden oder sonstige Erlaubnisse entfallen (z.B., wenn der Zweck der Verarbeitung dieser Daten entfallen ist oder sie f\u00fcr den Zweck nicht erforderlich sind).<\/p>\n<p>Sofern die Daten nicht gel\u00f6scht werden, weil sie f\u00fcr andere und gesetzlich zul\u00e4ssige Zwecke erforderlich sind, wird deren Verarbeitung auf diese Zwecke beschr\u00e4nkt. D.h., die Daten werden gesperrt und nicht f\u00fcr andere Zwecke verarbeitet. Das gilt z.B. f\u00fcr Daten, die aus handels- oder steuerrechtlichen Gr\u00fcnden aufbewahrt werden m\u00fcssen oder deren Speicherung zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen oder zum Schutz der Rechte einer anderen nat\u00fcrlichen oder juristischen Person erforderlich ist.<\/p>\n<p>Im Rahmen unserer Datenschutzhinweise k\u00f6nnen wir den Nutzern weitere Informationen zu der L\u00f6schung sowie zu der Aufbewahrung von Daten mitteilen, die speziell f\u00fcr die jeweiligen Verarbeitungsprozesses gelten.<\/p>\n<h2 id=\"m15\">\u00c4nderung und Aktualisierung der Datenschutzerkl\u00e4rung<\/h2>\n<p>Wir bitten Sie, sich regelm\u00e4\u00dfig \u00fcber den Inhalt unserer Datenschutzerkl\u00e4rung zu informieren. Wir passen die Datenschutzerkl\u00e4rung an, sobald die \u00c4nderungen der von uns durchgef\u00fchrten Datenverarbeitungen dies erforderlich machen. Wir informieren Sie, sobald durch die \u00c4nderungen eine Mitwirkungshandlung Ihrerseits (z.B. Einwilligung) oder eine sonstige individuelle Benachrichtigung erforderlich wird.<\/p>\n<p>Sofern wir in dieser Datenschutzerkl\u00e4rung Adressen und Kontaktinformationen von Unternehmen und Organisationen angeben, bitten wir zu beachten, dass die Adressen sich \u00fcber die Zeit \u00e4ndern k\u00f6nnen und bitten die Angaben vor Kontaktaufnahme zu pr\u00fcfen.<\/p>\n<h2 id=\"m10\">Rechte der betroffenen Personen<\/h2>\n<p>Ihnen stehen als Betroffene nach der DSGVO verschiedene Rechte zu, die sich insbesondere aus Art. 15 bis 21 DSGVO ergeben:<\/p>\n<ul>\n<li><strong>Widerspruchsrecht: Sie haben das Recht, aus Gr\u00fcnden, die sich aus Ihrer besonderen Situation ergeben, jederzeit gegen die Verarbeitung der Sie betreffenden personenbezogenen Daten, die aufgrund von Art. 6 Abs. 1 lit. e oder f DSGVO erfolgt, Widerspruch einzulegen; dies gilt auch f\u00fcr ein auf diese Bestimmungen gest\u00fctztes Profiling. Werden die Sie betreffenden personenbezogenen Daten verarbeitet, um Direktwerbung zu betreiben, haben Sie das Recht, jederzeit Widerspruch gegen die Verarbeitung der Sie betreffenden personenbezogenen Daten zum Zwecke derartiger Werbung einzulegen; dies gilt auch f\u00fcr das Profiling, soweit es mit solcher Direktwerbung in Verbindung steht.<\/strong><\/li>\n<li><strong>Widerrufsrecht bei Einwilligungen:<\/strong> Sie haben das Recht, erteilte Einwilligungen jederzeit zu widerrufen.<\/li>\n<li><strong>Auskunftsrecht:<\/strong> Sie haben das Recht, eine Best\u00e4tigung dar\u00fcber zu verlangen, ob betreffende Daten verarbeitet werden und auf Auskunft \u00fcber diese Daten sowie auf weitere Informationen und Kopie der Daten entsprechend den gesetzlichen Vorgaben.<\/li>\n<li><strong>Recht auf Berichtigung:<\/strong> Sie haben entsprechend den gesetzlichen Vorgaben das Recht, die Vervollst\u00e4ndigung der Sie betreffenden Daten oder die Berichtigung der Sie betreffenden unrichtigen Daten zu verlangen.<\/li>\n<li><strong>Recht auf L\u00f6schung und Einschr\u00e4nkung der Verarbeitung:<\/strong> Sie haben nach Ma\u00dfgabe der gesetzlichen Vorgaben das Recht, zu verlangen, dass Sie betreffende Daten unverz\u00fcglich gel\u00f6scht werden, bzw. alternativ nach Ma\u00dfgabe der gesetzlichen Vorgaben eine Einschr\u00e4nkung der Verarbeitung der Daten zu verlangen.<\/li>\n<li><strong>Recht auf Daten\u00fcbertragbarkeit:<\/strong> Sie haben das Recht, Sie betreffende Daten, die Sie uns bereitgestellt haben, nach Ma\u00dfgabe der gesetzlichen Vorgaben in einem strukturierten, g\u00e4ngigen und maschinenlesbaren Format zu erhalten oder deren \u00dcbermittlung an einen anderen Verantwortlichen zu fordern.<\/li>\n<li><strong>Beschwerde bei Aufsichtsbeh\u00f6rde:<\/strong> Entsprechend den gesetzlichen Vorgaben und unbeschadet eines anderweitigen verwaltungsrechtlichen oder gerichtlichen Rechtsbehelfs, haben Sie ferner das Recht, bei einer Datenschutzaufsichtsbeh\u00f6rde, insbesondere einer Aufsichtsbeh\u00f6rde im Mitgliedstaat, in dem Sie sich gew\u00f6hnlich aufhalten, der Aufsichtsbeh\u00f6rde Ihres Arbeitsplatzes oder des Ortes des mutma\u00dflichen Versto\u00dfes, eine Beschwerde einzulegen, wenn Sie der Ansicht sei sollten, dass die Verarbeitung der Ihre Person betreffenden personenbezogenen Daten gegen die DSGVO verst\u00f6\u00dft.<\/li>\n<\/ul>\n<h2 id=\"m42\">Begriffsdefinitionen<\/h2>\n<p>In diesem Abschnitt erhalten Sie eine \u00dcbersicht \u00fcber die in dieser Datenschutzerkl\u00e4rung verwendeten Begrifflichkeiten. Viele der Begriffe sind dem Gesetz entnommen und vor allem im Art. 4 DSGVO definiert. Die gesetzlichen Definitionen sind verbindlich. Die nachfolgenden Erl\u00e4uterungen sollen dagegen vor allem dem Verst\u00e4ndnis dienen. Die Begriffe sind alphabetisch sortiert.<\/p>\n<ul>\n<li><strong>IP-Masking:<\/strong> Als \u201eIP-Masking\u201d wird eine Methode bezeichnet, bei der das letzte Oktett, d.h., die letzten beiden Zahlen einer IP-Adresse, gel\u00f6scht wird, damit die IP-Adresse nicht mehr der eindeutigen Identifizierung einer Person dienen kann. Daher ist das IP-Masking ein Mittel zur Pseudonymisierung von Verarbeitungsverfahren, insbesondere im Onlinemarketing<\/li>\n<li><strong>Personenbezogene Daten:<\/strong> \u201ePersonenbezogene Daten\u201c sind alle Informationen, die sich auf eine identifizierte oder identifizierbare nat\u00fcrliche Person (im Folgenden \u201ebetroffene Person\u201c) beziehen; als identifizierbar wird eine nat\u00fcrliche Person angesehen, die direkt oder indirekt, insbesondere mittels Zuordnung zu einer Kennung wie einem Namen, zu einer Kennnummer, zu Standortdaten, zu einer Online-Kennung (z.B. Cookie) oder zu einem oder mehreren besonderen Merkmalen identifiziert werden kann, die Ausdruck der physischen, physiologischen, genetischen, psychischen, wirtschaftlichen, kulturellen oder sozialen Identit\u00e4t dieser nat\u00fcrlichen Person sind.<\/li>\n<li><strong>Profile mit nutzerbezogenen Informationen:<\/strong> Die Verarbeitung von \u201eProfilen mit nutzerbezogenen Informationen\u201c, bzw. kurz \u201eProfilen\u201c umfasst jede Art der automatisierten Verarbeitung personenbezogener Daten, die darin besteht, dass diese personenbezogenen Daten verwendet werden, um bestimmte pers\u00f6nliche Aspekte, die sich auf eine nat\u00fcrliche Person beziehen (je nach Art der Profilbildung k\u00f6nnen dazu unterschiedliche Informationen betreffend die Demographie, Verhalten und Interessen, wie z.B. die Interaktion mit Webseiten und deren Inhalten, etc.) zu analysieren, zu bewerten oder, um sie vorherzusagen (z.B. die Interessen an bestimmten Inhalten oder Produkten, das Klickverhalten auf einer Webseite oder den Aufenthaltsort). Zu Zwecken des Profilings werden h\u00e4ufig Cookies und Web-Beacons eingesetzt.<\/li>\n<li><strong>Reichweitenmessung:<\/strong> Die Reichweitenmessung (auch als Web Analytics bezeichnet) dient der Auswertung der Besucherstr\u00f6me eines Onlineangebotes und kann das Verhalten oder Interessen der Besucher an bestimmten Informationen, wie z.B. Inhalten von Webseiten, umfassen. Mit Hilfe der Reichweitenanalyse k\u00f6nnen Webseiteninhaber z.B. erkennen, zu welcher Zeit Besucher ihre Webseite besuchen und f\u00fcr welche Inhalte sie sich interessieren. Dadurch k\u00f6nnen sie z.B. die Inhalte der Webseite besser an die Bed\u00fcrfnisse ihrer Besucher anpassen. Zu Zwecken der Reichweitenanalyse werden h\u00e4ufig pseudonyme Cookies und Web-Beacons eingesetzt, um wiederkehrende Besucher zu erkennen und so genauere Analysen zur Nutzung eines Onlineangebotes zu erhalten.<\/li>\n<li><strong>Verantwortlicher:<\/strong> Als \u201eVerantwortlicher\u201c wird die nat\u00fcrliche oder juristische Person, Beh\u00f6rde, Einrichtung oder andere Stelle, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten entscheidet, bezeichnet.<\/li>\n<li><strong>Verarbeitung:<\/strong> \u201eVerarbeitung\u201c ist jeder mit oder ohne Hilfe automatisierter Verfahren ausgef\u00fchrte Vorgang oder jede solche Vorgangsreihe im Zusammenhang mit personenbezogenen Daten. Der Begriff reicht weit und umfasst praktisch jeden Umgang mit Daten, sei es das Erheben, das Auswerten, das Speichern, das \u00dcbermitteln oder das L\u00f6schen.<\/li>\n<\/ul>\n<figure class=\"wp-block-image\"><a href=\"https:\/\/datenschutz-generator.de\/?l=de\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"customize-unpreviewable\"><img decoding=\"async\" src=\"https:\/\/datenschutz-generator.de\/wp-content\/plugins\/ts-dsg\/images\/dsg-seal\/dsg-seal-pp-de.png\" alt=\"Rechtstext von Dr. Schwenke - f\u00fcr weitere Informationen bitte anklicken.\" \/><\/a><\/figure>\n<\/div>\n<\/div>\n<p><!--more--><br \/>\n<!-- {\"type\":\"layout\",\"children\":[{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"\n\n<p class=\\\"uk-article-title\\\">Datenschutzerkl\\u00e4rung<\\\/p>\",\"content_en_us\":\"Privacy Policy\",\"title_element\":\"h1\"}}]}]}]},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"style\":\"muted\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"\n\n<div class=\\\"uk-margin-medium\\\" property=\\\"text\\\">\\n\n\n<h2>Einleitung<\\\/h2>\\n\n\n<p>Mit der folgenden Datenschutzerkl\\u00e4rung m\\u00f6chten wir Sie dar\\u00fcber aufkl\\u00e4ren, welche Arten Ihrer personenbezogenen Daten (nachfolgend auch kurz als \\u201eDaten\\u201c bezeichnet) wir zu welchen Zwecken und in welchem Umfang verarbeiten. Die Datenschutzerkl\\u00e4rung gilt f\\u00fcr alle von uns durchgef\\u00fchrten Verarbeitungen personenbezogener Daten, sowohl im Rahmen der Erbringung unserer Leistungen als auch insbesondere auf unseren Webseiten, in mobilen Applikationen sowie innerhalb externer Onlinepr\\u00e4senzen, wie z.B. unserer Social-Media-Profile (nachfolgend zusammenfassend bezeichnet als \\u201eOnlineangebot\\u201c).<\\\/p>\\n\n\n<p>Die verwendeten Begriffe sind nicht geschlechtsspezifisch.<\\\/p>\\n\n\n<p>Stand: 20. April 2021<\\\/p>\\n\n\n<h2>Inhalts\\u00fcbersicht<\\\/h2>\\n\n\n<ul>\\n\n\n<li><a href=\\\"https:\\\/\\\/stage.fayence-steinzeug-vogt.de\\\/de\\\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m14\\\">Einleitung<\\\/a><\\\/li>\\n\n\n<li><a href=\\\"https:\\\/\\\/stage.fayence-steinzeug-vogt.de\\\/de\\\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m3\\\">Verantwortlicher<\\\/a><\\\/li>\\n\n\n<li><a href=\\\"https:\\\/\\\/stage.fayence-steinzeug-vogt.de\\\/de\\\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#mOverview\\\">\\u00dcbersicht der Verarbeitungen<\\\/a><\\\/li>\\n\n\n<li><a href=\\\"https:\\\/\\\/stage.fayence-steinzeug-vogt.de\\\/de\\\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m13\\\">Ma\\u00dfgebliche Rechtsgrundlagen<\\\/a><\\\/li>\\n\n\n<li><a href=\\\"https:\\\/\\\/stage.fayence-steinzeug-vogt.de\\\/de\\\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m27\\\">Sicherheitsma\\u00dfnahmen<\\\/a><\\\/li>\\n\n\n<li><a href=\\\"https:\\\/\\\/stage.fayence-steinzeug-vogt.de\\\/de\\\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m134\\\">Einsatz von Cookies<\\\/a><\\\/li>\\n\n\n<li><a href=\\\"https:\\\/\\\/stage.fayence-steinzeug-vogt.de\\\/de\\\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m225\\\">Bereitstellung des Onlineangebotes und Webhosting<\\\/a><\\\/li>\\n\n\n<li><a href=\\\"https:\\\/\\\/stage.fayence-steinzeug-vogt.de\\\/de\\\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m104\\\">Blogs und Publikationsmedien<\\\/a><\\\/li>\\n\n\n<li><a href=\\\"https:\\\/\\\/stage.fayence-steinzeug-vogt.de\\\/de\\\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m29\\\">Cloud-Dienste<\\\/a><\\\/li>\\n\n\n<li><a href=\\\"https:\\\/\\\/stage.fayence-steinzeug-vogt.de\\\/de\\\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m17\\\">Newsletter und elektronische Benachrichtigungen<\\\/a><\\\/li>\\n\n\n<li><a href=\\\"https:\\\/\\\/stage.fayence-steinzeug-vogt.de\\\/de\\\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m263\\\">Webanalyse, Monitoring und Optimierung<\\\/a><\\\/li>\\n\n\n<li><a href=\\\"https:\\\/\\\/stage.fayence-steinzeug-vogt.de\\\/de\\\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m136\\\">Pr\\u00e4senzen in sozialen Netzwerken (Social Media)<\\\/a><\\\/li>\\n\n\n<li><a href=\\\"https:\\\/\\\/stage.fayence-steinzeug-vogt.de\\\/de\\\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m328\\\">Plugins und eingebettete Funktionen sowie Inhalte<\\\/a><\\\/li>\\n\n\n<li><a href=\\\"https:\\\/\\\/stage.fayence-steinzeug-vogt.de\\\/de\\\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m12\\\">L\\u00f6schung von Daten<\\\/a><\\\/li>\\n\n\n<li><a href=\\\"https:\\\/\\\/stage.fayence-steinzeug-vogt.de\\\/de\\\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m15\\\">\\u00c4nderung und Aktualisierung der Datenschutzerkl\\u00e4rung<\\\/a><\\\/li>\\n\n\n<li><a href=\\\"https:\\\/\\\/stage.fayence-steinzeug-vogt.de\\\/de\\\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m10\\\">Rechte der betroffenen Personen<\\\/a><\\\/li>\\n\n\n<li><a href=\\\"https:\\\/\\\/stage.fayence-steinzeug-vogt.de\\\/de\\\/?page_id=7144&amp;customize_changeset_uuid=8f41766f-4c3d-486f-a9ea-c4f26756798a&amp;customize_theme=yootheme&amp;customize_messenger_channel=preview-0#m42\\\">Begriffsdefinitionen<\\\/a><\\\/li>\\n<\\\/ul>\\n\n\n<h2 id=\\\"m3\\\">Verantwortlicher<\\\/h2>\\n\n\n<p>Antiquit\\u00e4ten im Rathaus<br \\\/>Peter Vogt<br \\\/>Marienplatz 8<br \\\/>80331 M\\u00fcnchen<\\\/p>\\n\n\n<p>Vertretungsberechtigte Personen: Peter Vogt.<\\\/p>\\n\n\n<p>E-Mail-Adresse: verkauf(a)fayence-steinzeug-vogt.de.<\\\/p>\\n\n\n<p>Telefon: 089 294132.<\\\/p>\\n\n\n<p>Impressum: <a href=\\\"https:\\\/\\\/www.fayence-steinzeug-vogt.de\\\/de\\\/impressum\\\/\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/fayence-steinzeug-vogt.de\\\/impressum\\\/<\\\/a>.<\\\/p>\\n\n\n<h2 id=\\\"mOverview\\\">\\u00dcbersicht der Verarbeitungen<\\\/h2>\\n\n\n<p>Die nachfolgende \\u00dcbersicht fasst die Arten der verarbeiteten Daten und die Zwecke ihrer Verarbeitung zusammen und verweist auf die betroffenen Personen.<\\\/p>\\n\n\n<h3>Arten der verarbeiteten Daten<\\\/h3>\\n\n\n<ul>\\n\n\n<li>Event-Daten (Facebook) (\\u201eEvent-Daten\\u201c sind Daten, die z. B. via Facebook-Pixel (via Apps oder auf anderen Wegen) von uns an Facebook \\u00fcbermittelt werden k\\u00f6nnen und sich auf Personen oder deren Handlungen beziehen; Zu den Daten geh\\u00f6ren z. B. Angaben \\u00fcber Besuche auf Websites, Interaktionen mit Inhalten, Funktionen, Installationen von Apps, K\\u00e4ufe von Produkten, etc.; die Event-Daten werden zwecks Bildung von Zielgruppen f\\u00fcr Inhalte und Werbeinformationen (Custom Audiences) verarbeitet; Event Daten beinhalten nicht die eigentlichen Inhalte (wie z. B. verfasste Kommentare), keine Login-Informationen und keine Kontaktinformationen (also keine Namen, E-Mail-Adressen und Telefonnummern). Event Daten werden durch Facebook nach maximal zwei Jahren gel\\u00f6scht, die aus ihnen gebildeten Zielgruppen mit der L\\u00f6schung unseres Facebook-Kontos).<\\\/li>\\n\n\n<li>Bestandsdaten (z.B. Namen, Adressen).<\\\/li>\\n\n\n<li>Inhaltsdaten (z.B. Eingaben in Onlineformularen).<\\\/li>\\n\n\n<li>Kontaktdaten (z.B. E-Mail, Telefonnummern).<\\\/li>\\n\n\n<li>Meta-\\\/Kommunikationsdaten (z.B. Ger\\u00e4te-Informationen, IP-Adressen).<\\\/li>\\n\n\n<li>Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten).<\\\/li>\\n<\\\/ul>\\n\n\n<h3>Kategorien betroffener Personen<\\\/h3>\\n\n\n<ul>\\n\n\n<li>Besch\\u00e4ftigte (z.B. Angestellte, Bewerber, ehemalige Mitarbeiter).<\\\/li>\\n\n\n<li>Interessenten.<\\\/li>\\n\n\n<li>Kommunikationspartner.<\\\/li>\\n\n\n<li>Kunden.<\\\/li>\\n\n\n<li>Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\\\/li>\\n<\\\/ul>\\n\n\n<h3>Zwecke der Verarbeitung<\\\/h3>\\n\n\n<ul>\\n\n\n<li>Bereitstellung unseres Onlineangebotes und Nutzerfreundlichkeit.<\\\/li>\\n\n\n<li>B\\u00fcro- und Organisationsverfahren.<\\\/li>\\n\n\n<li>Direktmarketing (z.B. per E-Mail oder postalisch).<\\\/li>\\n\n\n<li>Feedback (z.B. Sammeln von Feedback via Online-Formular).<\\\/li>\\n\n\n<li>Marketing.<\\\/li>\\n\n\n<li>Kontaktanfragen und Kommunikation.<\\\/li>\\n\n\n<li>Profile mit nutzerbezogenen Informationen (Erstellen von Nutzerprofilen).<\\\/li>\\n\n\n<li>Reichweitenmessung (z.B. Zugriffsstatistiken, Erkennung wiederkehrender Besucher).<\\\/li>\\n\n\n<li>Sicherheitsma\\u00dfnahmen.<\\\/li>\\n\n\n<li>Erbringung vertragliche Leistungen und Kundenservice.<\\\/li>\\n<\\\/ul>\\n\n\n<h3 id=\\\"m13\\\">Ma\\u00dfgebliche Rechtsgrundlagen<\\\/h3>\\n\n\n<p>Nachfolgend erhalten Sie einen \\u00dcberblick \\u00fcber die Rechtsgrundlagen der DSGVO, die wir der Verarbeitung personenbezogener Daten zugrunde legen. Bitte beachten Sie, dass zus\\u00e4tzlich zu den Bestimmungen der DSGVO, nationale Datenschutzbestimmungen Ihres oder unseres Wohnsitz-, bzw. Sitzlandes zur Anwendung kommen k\\u00f6nnen. Sollten ferner im Einzelfall speziellere Rechtsgrundlagen ma\\u00dfgeblich sein, teilen wir Ihnen diese in der Datenschutzerkl\\u00e4rung mit.<\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>Einwilligung (Art. 6 Abs. 1 S. 1 lit. a. DSGVO)<\\\/strong> \\u2013 Die betroffene Person hat ihre Einwilligung in die Verarbeitung der sie betreffenden personenbezogenen Daten f\\u00fcr einen spezifischen Zweck oder mehrere bestimmte Zwecke gegeben.<\\\/li>\\n\n\n<li><strong>Vertragserf\\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO)<\\\/strong> \\u2013 Die Verarbeitung ist f\\u00fcr die Erf\\u00fcllung eines Vertrags, dessen Vertragspartei die betroffene Person ist, oder zur Durchf\\u00fchrung vorvertraglicher Ma\\u00dfnahmen erforderlich, die auf Anfrage der betroffenen Person erfolgen.<\\\/li>\\n\n\n<li><strong>Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO)<\\\/strong> \\u2013 Die Verarbeitung ist zur Wahrung der berechtigten Interessen des Verantwortlichen oder eines Dritten erforderlich, sofern nicht die Interessen oder Grundrechte und Grundfreiheiten der betroffenen Person, die den Schutz personenbezogener Daten erfordern, \\u00fcberwiegen.<\\\/li>\\n<\\\/ul>\\n\n\n<p><strong>Nationale Datenschutzregelungen in Deutschland<\\\/strong>: Zus\\u00e4tzlich zu den Datenschutzregelungen der Datenschutz-Grundverordnung gelten nationale Regelungen zum Datenschutz in Deutschland. Hierzu geh\\u00f6rt insbesondere das Gesetz zum Schutz vor Missbrauch personenbezogener Daten bei der Datenverarbeitung (Bundesdatenschutzgesetz \\u2013 BDSG). Das BDSG enth\\u00e4lt insbesondere Spezialregelungen zum Recht auf Auskunft, zum Recht auf L\\u00f6schung, zum Widerspruchsrecht, zur Verarbeitung besonderer Kategorien personenbezogener Daten, zur Verarbeitung f\\u00fcr andere Zwecke und zur \\u00dcbermittlung sowie automatisierten Entscheidungsfindung im Einzelfall einschlie\\u00dflich Profiling. Des Weiteren regelt es die Datenverarbeitung f\\u00fcr Zwecke des Besch\\u00e4ftigungsverh\\u00e4ltnisses (\\u00a7 26 BDSG), insbesondere im Hinblick auf die Begr\\u00fcndung, Durchf\\u00fchrung oder Beendigung von Besch\\u00e4ftigungsverh\\u00e4ltnissen sowie die Einwilligung von Besch\\u00e4ftigten. Ferner k\\u00f6nnen Landesdatenschutzgesetze der einzelnen Bundesl\\u00e4nder zur Anwendung gelangen.<\\\/p>\\n\n\n<h2 id=\\\"m27\\\">Sicherheitsma\\u00dfnahmen<\\\/h2>\\n\n\n<p>Wir treffen nach Ma\\u00dfgabe der gesetzlichen Vorgaben unter Ber\\u00fccksichtigung des Stands der Technik, der Implementierungskosten und der Art, des Umfangs, der Umst\\u00e4nde und der Zwecke der Verarbeitung sowie der unterschiedlichen Eintrittswahrscheinlichkeiten und des Ausma\\u00dfes der Bedrohung der Rechte und Freiheiten nat\\u00fcrlicher Personen geeignete technische und organisatorische Ma\\u00dfnahmen, um ein dem Risiko angemessenes Schutzniveau zu gew\\u00e4hrleisten.<\\\/p>\\n\n\n<p>Zu den Ma\\u00dfnahmen geh\\u00f6ren insbesondere die Sicherung der Vertraulichkeit, Integrit\\u00e4t und Verf\\u00fcgbarkeit von Daten durch Kontrolle des physischen und elektronischen Zugangs zu den Daten als auch des sie betreffenden Zugriffs, der Eingabe, der Weitergabe, der Sicherung der Verf\\u00fcgbarkeit und ihrer Trennung. Des Weiteren haben wir Verfahren eingerichtet, die eine Wahrnehmung von Betroffenenrechten, die L\\u00f6schung von Daten und Reaktionen auf die Gef\\u00e4hrdung der Daten gew\\u00e4hrleisten. Ferner ber\\u00fccksichtigen wir den Schutz personenbezogener Daten bereits bei der Entwicklung bzw. Auswahl von Hardware, Software sowie Verfahren entsprechend dem Prinzip des Datenschutzes, durch Technikgestaltung und durch datenschutzfreundliche Voreinstellungen.<\\\/p>\\n\n\n<p><strong>SSL-Verschl\\u00fcsselung (https)<\\\/strong>: Um Ihre via unser Online-Angebot \\u00fcbermittelten Daten zu sch\\u00fctzen, nutzen wir eine SSL-Verschl\\u00fcsselung. Sie erkennen derart verschl\\u00fcsselte Verbindungen an dem Pr\\u00e4fix https:\\\/\\\/ in der Adresszeile Ihres Browsers.<\\\/p>\\n\n\n<h2 id=\\\"m134\\\">Einsatz von Cookies<\\\/h2>\\n\n\n<p>Cookies sind Textdateien, die Daten von besuchten Websites oder Domains enthalten und von einem Browser auf dem Computer des Benutzers gespeichert werden. Ein Cookie dient in erster Linie dazu, die Informationen \\u00fcber einen Benutzer w\\u00e4hrend oder nach seinem Besuch innerhalb eines Onlineangebotes zu speichern. Zu den gespeicherten Angaben k\\u00f6nnen z.B. die Spracheinstellungen auf einer Webseite, der Loginstatus, ein Warenkorb oder die Stelle, an der ein Video geschaut wurde, geh\\u00f6ren. Zu dem Begriff der Cookies z\\u00e4hlen wir ferner andere Technologien, die die gleichen Funktionen wie Cookies erf\\u00fcllen (z.B., wenn Angaben der Nutzer anhand pseudonymer Onlinekennzeichnungen gespeichert werden, auch als \\u201eNutzer-IDs\\u201c bezeichnet)<\\\/p>\\n\n\n<p><strong>Die folgenden Cookie-Typen und Funktionen werden unterschieden:<\\\/strong><\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>Tempor\\u00e4re Cookies (auch: Session- oder Sitzungs-Cookies):<\\\/strong>\\u00a0Tempor\\u00e4re Cookies werden sp\\u00e4testens gel\\u00f6scht, nachdem ein Nutzer ein Online-Angebot verlassen und seinen Browser geschlossen hat.<\\\/li>\\n\n\n<li><strong>Permanente Cookies:<\\\/strong>\\u00a0Permanente Cookies bleiben auch nach dem Schlie\\u00dfen des Browsers gespeichert. So kann beispielsweise der Login-Status gespeichert oder bevorzugte Inhalte direkt angezeigt werden, wenn der Nutzer eine Website erneut besucht. Ebenso k\\u00f6nnen die Interessen von Nutzern, die zur Reichweitenmessung oder zu Marketingzwecken verwendet werden, in einem solchen Cookie gespeichert werden.<\\\/li>\\n\n\n<li><strong>First-Party-Cookies:<\\\/strong>\\u00a0First-Party-Cookies werden von uns selbst gesetzt.<\\\/li>\\n\n\n<li><strong>Third-Party-Cookies (auch: Drittanbieter-Cookies)<\\\/strong>: Drittanbieter-Cookies werden haupts\\u00e4chlich von Werbetreibenden (sog. Dritten) verwendet, um Benutzerinformationen zu verarbeiten.<\\\/li>\\n\n\n<li><strong>Notwendige (auch: essentielle oder unbedingt erforderliche) Cookies:<\\\/strong> Cookies k\\u00f6nnen zum einen f\\u00fcr den Betrieb einer Webseite unbedingt erforderlich sein (z.B. um Logins oder andere Nutzereingaben zu speichern oder aus Gr\\u00fcnden der Sicherheit).<\\\/li>\\n\n\n<li><strong>Statistik-, Marketing- und Personalisierungs-Cookies<\\\/strong>: Ferner werden Cookies im Regelfall auch im Rahmen der Reichweitenmessung eingesetzt sowie dann, wenn die Interessen eines Nutzers oder sein Verhalten (z.B. Betrachten bestimmter Inhalte, Nutzen von Funktionen etc.) auf einzelnen Webseiten in einem Nutzerprofil gespeichert werden. Solche Profile dienen dazu, den Nutzern z.B. Inhalte anzuzeigen, die ihren potentiellen Interessen entsprechen. Dieses Verfahren wird auch als \\u201eTracking\\u201c, d.h., Nachverfolgung der potentiellen Interessen der Nutzer bezeichnet. Soweit wir Cookies oder \\u201eTracking\\u201c-Technologien einsetzen, informieren wir Sie gesondert in unserer Datenschutzerkl\\u00e4rung oder im Rahmen der Einholung einer Einwilligung.<\\\/li>\\n<\\\/ul>\\n\n\n<p><strong>Hinweise zu Rechtsgrundlagen:<\\\/strong> Auf welcher Rechtsgrundlage wir Ihre personenbezogenen Daten mit Hilfe von Cookies verarbeiten, h\\u00e4ngt davon ab, ob wir Sie um eine Einwilligung bitten. Falls dies zutrifft und Sie in die Nutzung von Cookies einwilligen, ist die Rechtsgrundlage der Verarbeitung Ihrer Daten die erkl\\u00e4rte Einwilligung. Andernfalls werden die mithilfe von Cookies verarbeiteten Daten auf Grundlage unserer berechtigten Interessen (z.B. an einem betriebswirtschaftlichen Betrieb unseres Onlineangebotes und dessen Verbesserung) verarbeitet oder, wenn der Einsatz von Cookies erforderlich ist, um unsere vertraglichen Verpflichtungen zu erf\\u00fcllen.<\\\/p>\\n\n\n<p><strong>Speicherdauer: <\\\/strong>Sofern wir Ihnen keine expliziten Angaben zur Speicherdauer von permanenten Cookies mitteilen (z. B. im Rahmen eines sog. Cookie-Opt-Ins), gehen Sie bitte davon aus, dass die Speicherdauer bis zu zwei Jahre betragen kann.<\\\/p>\\n\n\n<p><strong>Allgemeine Hinweise zum Widerruf und Widerspruch (Opt-Out):<\\\/strong> Abh\\u00e4ngig davon, ob die Verarbeitung auf Grundlage einer Einwilligung oder gesetzlichen Erlaubnis erfolgt, haben Sie jederzeit die M\\u00f6glichkeit, eine erteilte Einwilligung zu widerrufen oder der Verarbeitung Ihrer Daten durch Cookie-Technologien zu widersprechen (zusammenfassend als \\u201eOpt-Out\\u201c bezeichnet). Sie k\\u00f6nnen Ihren Widerspruch zun\\u00e4chst mittels der Einstellungen Ihres Browsers erkl\\u00e4ren, z.B., indem Sie die Nutzung von Cookies deaktivieren (wobei hierdurch auch die Funktionsf\\u00e4higkeit unseres Onlineangebotes eingeschr\\u00e4nkt werden kann). Ein Widerspruch gegen den Einsatz von Cookies zu Zwecken des Onlinemarketings kann auch mittels einer Vielzahl von Diensten, vor allem im Fall des Trackings, \\u00fcber die Webseiten <a href=\\\"https:\\\/\\\/optout.aboutads.info\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/optout.aboutads.info<\\\/a> und <a href=\\\"https:\\\/\\\/www.youronlinechoices.com\\\/\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.youronlinechoices.com\\\/<\\\/a> erkl\\u00e4rt werden. Daneben k\\u00f6nnen Sie weitere Widerspruchshinweise im Rahmen der Angaben zu den eingesetzten Dienstleistern und Cookies erhalten.<\\\/p>\\n\n\n<p><strong>Verarbeitung von Cookie-Daten auf Grundlage einer Einwilligung<\\\/strong>: Wir setzen ein Verfahren zum Cookie-Einwilligungs-Management ein, in dessen Rahmen die Einwilligungen der Nutzer in den Einsatz von Cookies, bzw. der im Rahmen des Cookie-Einwilligungs-Management-Verfahrens genannten Verarbeitungen und Anbieter eingeholt sowie von den Nutzern verwaltet und widerrufen werden k\\u00f6nnen. Hierbei wird die Einwilligungserkl\\u00e4rung gespeichert, um deren Abfrage nicht erneut wiederholen zum m\\u00fcssen und die Einwilligung entsprechend der gesetzlichen Verpflichtung nachweisen zu k\\u00f6nnen. Die Speicherung kann serverseitig und\\\/oder in einem Cookie (sogenanntes Opt-In-Cookie, bzw. mithilfe vergleichbarer Technologien) erfolgen, um die Einwilligung einem Nutzer, bzw. dessen Ger\\u00e4t zuordnen zu k\\u00f6nnen. Vorbehaltlich individueller Angaben zu den Anbietern von Cookie-Management-Diensten, gelten die folgenden Hinweise: Die Dauer der Speicherung der Einwilligung kann bis zu zwei Jahren betragen. Hierbei wird ein pseudonymer Nutzer-Identifikator gebildet und mit dem Zeitpunkt der Einwilligung, Angaben zur Reichweite der Einwilligung (z. B. welche Kategorien von Cookies und\\\/oder Diensteanbieter) sowie dem Browser, System und verwendeten Endger\\u00e4t gespeichert.<\\\/p>\\n\n\n<p>Cookie-Einstellungen\\\/ -Widerspruchsm\\u00f6glichkeit:<\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>Verarbeitete Datenarten:<\\\/strong> Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\\\/Kommunikationsdaten (z.B. Ger\\u00e4te-Informationen, IP-Adressen).<\\\/li>\\n\n\n<li><strong>Betroffene Personen:<\\\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\\\/li>\\n\n\n<li><strong>Rechtsgrundlagen:<\\\/strong> Einwilligung (Art. 6 Abs. 1 S. 1 lit. a. DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO).<\\\/li>\\n<\\\/ul>\\n\n\n<p><strong>Eingesetzte Dienste und Diensteanbieter:<\\\/strong><\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>Cookiebot:<\\\/strong> Cookie-Einwilligungs-Management; Dienstanbieter: Cybot A\\\/S, Havnegade 39, 1058 Kopenhagen, D\\u00e4nemark; Website: <a href=\\\"https:\\\/\\\/www.cookiebot.com\\\/de\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.cookiebot.com\\\/de<\\\/a>; Datenschutzerkl\\u00e4rung: <a href=\\\"https:\\\/\\\/www.cookiebot.com\\\/de\\\/privacy-policy\\\/\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.cookiebot.com\\\/de\\\/privacy-policy\\\/<\\\/a>; Gespeicherte Daten (auf dem Server des Dienstleisters): Die IP-Nummer des Nutzers in anonymisierter Form (die letzten drei Ziffern werden auf 0 gesetzt), Datum und Uhrzeit der Zustimmung, Browserangaben, die URL, von der die Zustimmung gesendet wurde, Ein anonymer, zuf\\u00e4lliger und verschl\\u00fcsselter Schl\\u00fcsselwert; der Einwilligungsstatus des Nutzers.<\\\/li>\\n<\\\/ul>\\n\n\n<h2 id=\\\"m225\\\">Bereitstellung des Onlineangebotes und Webhosting<\\\/h2>\\n\n\n<p>Um unser Onlineangebot sicher und effizient bereitstellen zu k\\u00f6nnen, nehmen wir die Leistungen von einem oder mehreren Webhosting-Anbietern in Anspruch, von deren Servern (bzw. von ihnen verwalteten Servern) das Onlineangebot abgerufen werden kann. Zu diesen Zwecken k\\u00f6nnen wir Infrastruktur- und Plattformdienstleistungen, Rechenkapazit\\u00e4t, Speicherplatz und Datenbankdienste sowie Sicherheitsleistungen und technische Wartungsleistungen in Anspruch nehmen.<\\\/p>\\n\n\n<p>Zu den im Rahmen der Bereitstellung des Hostingangebotes verarbeiteten Daten k\\u00f6nnen alle die Nutzer unseres Onlineangebotes betreffenden Angaben geh\\u00f6ren, die im Rahmen der Nutzung und der Kommunikation anfallen. Hierzu geh\\u00f6ren regelm\\u00e4\\u00dfig die IP-Adresse, die notwendig ist, um die Inhalte von Onlineangeboten an Browser ausliefern zu k\\u00f6nnen, und alle innerhalb unseres Onlineangebotes oder von Webseiten get\\u00e4tigten Eingaben.<\\\/p>\\n\n\n<p><strong>E-Mail-Versand und -Hosting<\\\/strong>: Die von uns in Anspruch genommenen Webhosting-Leistungen umfassen ebenfalls den Versand, den Empfang sowie die Speicherung von E-Mails. Zu diesen Zwecken werden die Adressen der Empf\\u00e4nger sowie Absender als auch weitere Informationen betreffend den E-Mailversand (z.B. die beteiligten Provider) sowie die Inhalte der jeweiligen E-Mails verarbeitet. Die vorgenannten Daten k\\u00f6nnen ferner zu Zwecken der Erkennung von SPAM verarbeitet werden. Wir bitten darum, zu beachten, dass E-Mails im Internet grunds\\u00e4tzlich nicht verschl\\u00fcsselt versendet werden. Im Regelfall werden E-Mails zwar auf dem Transportweg verschl\\u00fcsselt, aber (sofern kein sogenanntes Ende-zu-Ende-Verschl\\u00fcsselungsverfahren eingesetzt wird) nicht auf den Servern, von denen sie abgesendet und empfangen werden. Wir k\\u00f6nnen daher f\\u00fcr den \\u00dcbertragungsweg der E-Mails zwischen dem Absender und dem Empfang auf unserem Server keine Verantwortung \\u00fcbernehmen.<\\\/p>\\n\n\n<p><strong>Erhebung von Zugriffsdaten und Logfiles<\\\/strong>: Wir selbst (bzw. unser Webhostinganbieter) erheben Daten zu jedem Zugriff auf den Server (sogenannte Serverlogfiles). Zu den Serverlogfiles k\\u00f6nnen die Adresse und Name der abgerufenen Webseiten und Dateien, Datum und Uhrzeit des Abrufs, \\u00fcbertragene Datenmengen, Meldung \\u00fcber erfolgreichen Abruf, Browsertyp nebst Version, das Betriebssystem des Nutzers, Referrer URL (die zuvor besuchte Seite) und im Regelfall IP-Adressen und der anfragende Provider geh\\u00f6ren.<\\\/p>\\n\n\n<p>Die Serverlogfiles k\\u00f6nnen zum einen zu Zwecken der Sicherheit eingesetzt werden, z.B., um eine \\u00dcberlastung der Server zu vermeiden (insbesondere im Fall von missbr\\u00e4uchlichen Angriffen, sogenannten DDoS-Attacken) und zum anderen, um die Auslastung der Server und ihre Stabilit\\u00e4t sicherzustellen.<\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>Verarbeitete Datenarten:<\\\/strong> Inhaltsdaten (z.B. Eingaben in Onlineformularen), Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\\\/Kommunikationsdaten (z.B. Ger\\u00e4te-Informationen, IP-Adressen).<\\\/li>\\n\n\n<li><strong>Betroffene Personen:<\\\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\\\/li>\\n\n\n<li><strong>Zwecke der Verarbeitung:<\\\/strong> Bereitstellung unseres Onlineangebotes und Nutzerfreundlichkeit.<\\\/li>\\n\n\n<li><strong>Rechtsgrundlagen:<\\\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO).<\\\/li>\\n<\\\/ul>\\n\n\n<p><strong>Eingesetzte Dienste und Diensteanbieter:<\\\/strong><\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>goneo:<\\\/strong> Leistungen auf dem Gebiet der Bereitstellung von informationstechnischer Infrastruktur und verbundenen Dienstleistungen (z.B. Speicherplatz und\\\/oder Rechenkapazit\\u00e4ten); Dienstanbieter: goneo Internet GmbH, Dresdener Stra\\u00dfe 18, 32423 Minden, Deutschland; Website: <a href=\\\"https:\\\/\\\/www.goneo.de\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.goneo.de<\\\/a>; Datenschutzerkl\\u00e4rung: <a href=\\\"https:\\\/\\\/www.goneo.de\\\/hilfe_kontakt\\\/datenschutz.html\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.goneo.de\\\/hilfe_kontakt\\\/datenschutz.html<\\\/a>.<\\\/li>\\n<\\\/ul>\\n\n\n<h2 id=\\\"m104\\\">Blogs und Publikationsmedien<\\\/h2>\\n\n\n<p>Wir nutzen Blogs oder vergleichbare Mittel der Onlinekommunikation und Publikation (nachfolgend \\u201ePublikationsmedium\\u201c). Die Daten der Leser werden f\\u00fcr die Zwecke des Publikationsmediums nur insoweit verarbeitet, als es f\\u00fcr dessen Darstellung und die Kommunikation zwischen Autoren und Lesern oder aus Gr\\u00fcnden der Sicherheit erforderlich ist. Im \\u00dcbrigen verweisen wir auf die Informationen zur Verarbeitung der Besucher unseres Publikationsmediums im Rahmen dieser Datenschutzhinweise.<\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>Verarbeitete Datenarten:<\\\/strong> Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail, Telefonnummern), Inhaltsdaten (z.B. Eingaben in Onlineformularen), Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\\\/Kommunikationsdaten (z.B. Ger\\u00e4te-Informationen, IP-Adressen).<\\\/li>\\n\n\n<li><strong>Betroffene Personen:<\\\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\\\/li>\\n\n\n<li><strong>Zwecke der Verarbeitung:<\\\/strong> Erbringung vertragliche Leistungen und Kundenservice, Feedback (z.B. Sammeln von Feedback via Online-Formular), Sicherheitsma\\u00dfnahmen.<\\\/li>\\n\n\n<li><strong>Rechtsgrundlagen:<\\\/strong> Vertragserf\\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO).<\\\/li>\\n<\\\/ul>\\n\n\n<p><strong>Eingesetzte Dienste und Diensteanbieter:<\\\/strong><\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>UpdraftPlus:<\\\/strong> Backup-Software und Backup-Speicherung; Dienstanbieter: Simba Hosting Ltd., 11, Barringer Way, St. Neots, Cambs., PE19 1LW, GB; Website: <a href=\\\"https:\\\/\\\/updraftplus.com\\\/\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/updraftplus.com\\\/<\\\/a>; Datenschutzerkl\\u00e4rung: <a href=\\\"https:\\\/\\\/updraftplus.com\\\/data-protection-and-privacy-centre\\\/\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/updraftplus.com\\\/data-protection-and-privacy-centre\\\/<\\\/a>.<\\\/li>\\n\n\n<li><strong>Wordfence:<\\\/strong> Firewall und Sicherheits- sowie Fehlererkennungsfunktionen; Dienstanbieter: Defiant, Inc., 800 5th Ave Ste 4100, Seattle, WA 98104, USA; Website: <a href=\\\"https:\\\/\\\/www.wordfence.com\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.wordfence.com<\\\/a>; Datenschutzerkl\\u00e4rung: <a href=\\\"https:\\\/\\\/www.wordfence.com\\\/privacy-policy\\\/\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.wordfence.com\\\/privacy-policy\\\/<\\\/a>; Standardvertragsklauseln (Gew\\u00e4hrleistung Datenschutzniveau bei Verarbeitung in Drittl\\u00e4ndern): <a href=\\\"https:\\\/\\\/www.wordfence.com\\\/gdpr\\\/dpa.pdf\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.wordfence.com\\\/gdpr\\\/dpa.pdf<\\\/a>.<\\\/li>\\n<\\\/ul>\\n\n\n<h2 id=\\\"m29\\\">Cloud-Dienste<\\\/h2>\\n\n\n<p>Wir nutzen \\u00fcber das Internet zug\\u00e4ngliche und auf den Servern ihrer Anbieter ausgef\\u00fchrte Softwaredienste (sogenannte \\u201eCloud-Dienste\\u201c, auch bezeichnet als \\u201eSoftware as a Service\\u201c) f\\u00fcr die folgenden Zwecke: Dokumentenspeicherung und Verwaltung, Kalenderverwaltung, E-Mail-Versand, Tabellenkalkulationen und Pr\\u00e4sentationen, Austausch von Dokumenten, Inhalten und Informationen mit bestimmten Empf\\u00e4ngern oder Ver\\u00f6ffentlichung von Webseiten, Formularen oder sonstigen Inhalten und Informationen sowie Chats und Teilnahme an Audio- und Videokonferenzen.<\\\/p>\\n\n\n<p>In diesem Rahmen k\\u00f6nnen personenbezogenen Daten verarbeitet und auf den Servern der Anbieter gespeichert werden, soweit diese Bestandteil von Kommunikationsvorg\\u00e4ngen mit uns sind oder von uns sonst, wie im Rahmen dieser Datenschutzerkl\\u00e4rung dargelegt, verarbeitet werden. Zu diesen Daten k\\u00f6nnen insbesondere Stammdaten und Kontaktdaten der Nutzer, Daten zu Vorg\\u00e4ngen, Vertr\\u00e4gen, sonstigen Prozessen und deren Inhalte geh\\u00f6ren. Die Anbieter der Cloud-Dienste verarbeiten ferner Nutzungsdaten und Metadaten, die von ihnen zu Sicherheitszwecken und zur Serviceoptimierung verwendet werden.<\\\/p>\\n\n\n<p>Sofern wir mit Hilfe der Cloud-Dienste f\\u00fcr andere Nutzer oder \\u00f6ffentlich zug\\u00e4ngliche Webseiten Formulare o.a. Dokumente und Inhalte bereitstellen, k\\u00f6nnen die Anbieter Cookies auf den Ger\\u00e4ten der Nutzer f\\u00fcr Zwecke der Webanalyse oder, um sich Einstellungen der Nutzer (z.B. im Fall der Mediensteuerung) zu merken, speichern.<\\\/p>\\n\n\n<p><strong>Hinweise zu Rechtsgrundlagen:<\\\/strong> Sofern wir um eine Einwilligung in den Einsatz der Cloud-Dienste bitten, ist die Rechtsgrundlage der Verarbeitung die Einwilligung. Ferner kann deren Einsatz ein Bestandteil unserer (vor)vertraglichen Leistungen sein, sofern der Einsatz der Cloud-Dienste in diesem Rahmen vereinbart wurde. Ansonsten werden die Daten der Nutzer auf Grundlage unserer berechtigten Interessen (d.h., Interesse an effizienten und sicheren Verwaltungs- und Kollaborationsprozessen) verarbeitet<\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>Verarbeitete Datenarten:<\\\/strong> Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail, Telefonnummern), Inhaltsdaten (z.B. Eingaben in Onlineformularen), Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\\\/Kommunikationsdaten (z.B. Ger\\u00e4te-Informationen, IP-Adressen).<\\\/li>\\n\n\n<li><strong>Betroffene Personen:<\\\/strong> Kunden, Besch\\u00e4ftigte (z.B. Angestellte, Bewerber, ehemalige Mitarbeiter), Interessenten, Kommunikationspartner.<\\\/li>\\n\n\n<li><strong>Zwecke der Verarbeitung:<\\\/strong> B\\u00fcro- und Organisationsverfahren.<\\\/li>\\n\n\n<li><strong>Rechtsgrundlagen:<\\\/strong> Einwilligung (Art. 6 Abs. 1 S. 1 lit. a. DSGVO), Vertragserf\\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO).<\\\/li>\\n<\\\/ul>\\n\n\n<p><strong>Eingesetzte Dienste und Diensteanbieter:<\\\/strong><\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>Microsoft Clouddienste:<\\\/strong> Cloud-Speicher-Dienste; Dienstanbieter: Microsoft Corporation, One Microsoft Way, Redmond, WA 98052-6399 USA; Website: <a href=\\\"https:\\\/\\\/microsoft.com\\\/de-de\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/microsoft.com\\\/de-de<\\\/a>; Datenschutzerkl\\u00e4rung: <a href=\\\"https:\\\/\\\/privacy.microsoft.com\\\/de-de\\\/privacystatement\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/privacy.microsoft.com\\\/de-de\\\/privacystatement<\\\/a>, Sicherheitshinweise: <a href=\\\"https:\\\/\\\/www.microsoft.com\\\/de-de\\\/trustcenter\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.microsoft.com\\\/de-de\\\/trustcenter<\\\/a>.<\\\/li>\\n<\\\/ul>\\n\n\n<h2 id=\\\"m17\\\">Newsletter und elektronische Benachrichtigungen<\\\/h2>\\n\n\n<p>Wir versenden Newsletter, E-Mails und weitere elektronische Benachrichtigungen (nachfolgend \\u201eNewsletter\\u201c) nur mit der Einwilligung der Empf\\u00e4nger oder einer gesetzlichen Erlaubnis. Sofern im Rahmen einer Anmeldung zum Newsletter dessen Inhalte konkret umschrieben werden, sind sie f\\u00fcr die Einwilligung der Nutzer ma\\u00dfgeblich. Im \\u00dcbrigen enthalten unsere Newsletter Informationen zu unseren Leistungen und uns.<\\\/p>\\n\n\n<p>Um sich zu unseren Newslettern anzumelden, reicht es grunds\\u00e4tzlich aus, wenn Sie Ihre E-Mail-Adresse angeben. Wir k\\u00f6nnen Sie jedoch bitten, einen Namen, zwecks pers\\u00f6nlicher Ansprache im Newsletter, oder weitere Angaben, sofern diese f\\u00fcr die Zwecke des Newsletters erforderlich sind, zu t\\u00e4tigen.<\\\/p>\\n\n\n<p><strong>Double-Opt-In-Verfahren:<\\\/strong> Die Anmeldung zu unserem Newsletter erfolgt grunds\\u00e4tzlich in einem sogenannte Double-Opt-In-Verfahren. D.h., Sie erhalten nach der Anmeldung eine E-Mail, in der Sie um die Best\\u00e4tigung Ihrer Anmeldung gebeten werden. Diese Best\\u00e4tigung ist notwendig, damit sich niemand mit fremden E-Mail-Adressen anmelden kann. Die Anmeldungen zum Newsletter werden protokolliert, um den Anmeldeprozess entsprechend den rechtlichen Anforderungen nachweisen zu k\\u00f6nnen. Hierzu geh\\u00f6rt die Speicherung des Anmelde- und des Best\\u00e4tigungszeitpunkts als auch der IP-Adresse. Ebenso werden die \\u00c4nderungen Ihrer bei dem Versanddienstleister gespeicherten Daten protokolliert.<\\\/p>\\n\n\n<p><strong>L\\u00f6schung und Einschr\\u00e4nkung der Verarbeitung:<\\\/strong> Wir k\\u00f6nnen die ausgetragenen E-Mail-Adressen bis zu drei Jahren auf Grundlage unserer berechtigten Interessen speichern, bevor wir sie l\\u00f6schen, um eine ehemals gegebene Einwilligung nachweisen zu k\\u00f6nnen. Die Verarbeitung dieser Daten wird auf den Zweck einer m\\u00f6glichen Abwehr von Anspr\\u00fcchen beschr\\u00e4nkt. Ein individueller L\\u00f6schungsantrag ist jederzeit m\\u00f6glich, sofern zugleich das ehemalige Bestehen einer Einwilligung best\\u00e4tigt wird. Im Fall von Pflichten zur dauerhaften Beachtung von Widerspr\\u00fcchen behalten wir uns die Speicherung der E-Mail-Adresse alleine zu diesem Zweck in einer Sperrliste (sogenannte \\u201eBlocklist\\u201c) vor.<\\\/p>\\n\n\n<p>Die Protokollierung des Anmeldeverfahrens erfolgt auf Grundlage unserer berechtigten Interessen zu Zwecken des Nachweises seines ordnungsgem\\u00e4\\u00dfen Ablaufs. Soweit wir einen Dienstleister mit dem Versand von E-Mails beauftragen, erfolgt dies auf Grundlage unserer berechtigten Interessen an einem effizienten und sicheren Versandsystem.<\\\/p>\\n\n\n<p><strong>Hinweise zu Rechtsgrundlagen:<\\\/strong> Der Versand der Newsletter erfolgt auf Grundlage einer Einwilligung der Empf\\u00e4nger oder, falls eine Einwilligung nicht erforderlich ist, auf Grundlage unserer berechtigten Interessen am Direktmarketing, sofern und soweit diese gesetzlich, z.B. im Fall von Bestandskundenwerbung, erlaubt ist. Soweit wir einen Dienstleister mit dem Versand von E-Mails beauftragen, geschieht dies auf der Grundlage unserer berechtigten Interessen. Das Registrierungsverfahren wird auf der Grundlage unserer berechtigten Interessen aufgezeichnet, um nachzuweisen, dass es in \\u00dcbereinstimmung mit dem Gesetz durchgef\\u00fchrt wurde.<\\\/p>\\n\n\n<p>Inhalte: Informationen zu unserem Angebot an Antiquit\\u00e4ten, Veranstaltungen und Fachinformationen zu den Objekten.<\\\/p>\\n\n\n<p><strong>Messung von \\u00d6ffnungs- und Klickraten<\\\/strong>: Die Newsletter enthalten einen sogenannte \\u201eweb-beacon\\u201c, d.h., eine pixelgro\\u00dfe Datei, die beim \\u00d6ffnen des Newsletters von unserem Server, bzw., sofern wir einen Versanddienstleister einsetzen, von dessen Server abgerufen wird. Im Rahmen dieses Abrufs werden zun\\u00e4chst technische Informationen, wie Informationen zum Browser und Ihrem System, als auch Ihre IP-Adresse und der Zeitpunkt des Abrufs, erhoben.<\\\/p>\\n\n\n<p>Diese Informationen werden zur technischen Verbesserung unseres Newsletters anhand der technischen Daten oder der Zielgruppen und ihres Leseverhaltens auf Basis ihrer Abruforte (die mit Hilfe der IP-Adresse bestimmbar sind) oder der Zugriffszeiten genutzt. Diese Analyse beinhaltet ebenfalls die Feststellung, ob die Newsletter ge\\u00f6ffnet werden, wann sie ge\\u00f6ffnet werden und welche Links geklickt werden. Diese Informationen werden den einzelnen Newsletterempf\\u00e4ngern zugeordnet und in deren Profilen bis zu deren L\\u00f6schung gespeichert. Die Auswertungen dienen uns dazu, die Lesegewohnheiten unserer Nutzer zu erkennen und unsere Inhalte an sie anzupassen oder unterschiedliche Inhalte entsprechend den Interessen unserer Nutzer zu versenden.<\\\/p>\\n\n\n<p>Die Messung der \\u00d6ffnungsraten und der Klickraten sowie Speicherung der Messergebnisse in den Profilen der Nutzer sowie deren weitere Verarbeitung erfolgen auf Grundlage einer Einwilligung der Nutzer.<\\\/p>\\n\n\n<p>Ein getrennter Widerruf der Erfolgsmessung ist leider nicht m\\u00f6glich, in diesem Fall muss das gesamte Newsletterabonnement gek\\u00fcndigt, bzw. muss ihm widersprochen werden. In diesem Fall werden die gespeicherten Profilinformationen gel\\u00f6scht.<\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>Verarbeitete Datenarten:<\\\/strong> Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail, Telefonnummern), Meta-\\\/Kommunikationsdaten (z.B. Ger\\u00e4te-Informationen, IP-Adressen), Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten).<\\\/li>\\n\n\n<li><strong>Betroffene Personen:<\\\/strong> Kommunikationspartner.<\\\/li>\\n\n\n<li><strong>Zwecke der Verarbeitung:<\\\/strong> Direktmarketing (z.B. per E-Mail oder postalisch).<\\\/li>\\n\n\n<li><strong>Rechtsgrundlagen:<\\\/strong> Einwilligung (Art. 6 Abs. 1 S. 1 lit. a. DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO).<\\\/li>\\n\n\n<li><strong>Widerspruchsm\\u00f6glichkeit (Opt-Out):<\\\/strong> Sie k\\u00f6nnen den Empfang unseres Newsletters jederzeit k\\u00fcndigen, d.h. Ihre Einwilligungen widerrufen, bzw. dem weiteren Empfang widersprechen. Einen Link zur K\\u00fcndigung des Newsletters finden Sie entweder am Ende eines jeden Newsletters oder k\\u00f6nnen sonst eine der oben angegebenen Kontaktm\\u00f6glichkeiten, vorzugsw\\u00fcrdig E-Mail, hierzu nutzen.<\\\/li>\\n<\\\/ul>\\n\n\n<p><strong>Eingesetzte Dienste und Diensteanbieter:<\\\/strong><\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>CleverReach:<\\\/strong> E-Mail-Marketing-Plattform; Dienstanbieter: CleverReach GmbH &amp; Co. KG, \\\/\\\/CRASH Building, Schafj\\u00fcckenweg 2, 26180 Rastede, Deutschland; Website: <a href=\\\"https:\\\/\\\/www.cleverreach.com\\\/de\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.cleverreach.com\\\/de<\\\/a>; Datenschutzerkl\\u00e4rung: <a href=\\\"https:\\\/\\\/www.cleverreach.com\\\/de\\\/datenschutz\\\/\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.cleverreach.com\\\/de\\\/datenschutz\\\/<\\\/a>.<\\\/li>\\n<\\\/ul>\\n\n\n<h2 id=\\\"m263\\\">Webanalyse, Monitoring und Optimierung<\\\/h2>\\n\n\n<p>Die Webanalyse (auch als \\u201eReichweitenmessung\\u201c bezeichnet) dient der Auswertung der Besucherstr\\u00f6me unseres Onlineangebotes und kann Verhalten, Interessen oder demographische Informationen zu den Besuchern, wie z.B. das Alter oder das Geschlecht, als pseudonyme Werte umfassen. Mit Hilfe der Reichweitenanalyse k\\u00f6nnen wir z.B. erkennen, zu welcher Zeit unser Onlineangebot oder dessen Funktionen oder Inhalte am h\\u00e4ufigsten genutzt werden oder zur Wiederverwendung einladen. Ebenso k\\u00f6nnen wir nachvollziehen, welche Bereiche der Optimierung bed\\u00fcrfen.<\\\/p>\\n\n\n<p>Neben der Webanalyse k\\u00f6nnen wir auch Testverfahren einsetzen, um z.B. unterschiedliche Versionen unseres Onlineangebotes oder seiner Bestandteile zu testen und optimieren.<\\\/p>\\n\n\n<p>Zu diesen Zwecken k\\u00f6nnen sogenannte Nutzerprofile angelegt und in einer Datei (sogenannte \\u201eCookie\\u201c) gespeichert oder \\u00e4hnliche Verfahren mit dem gleichen Zweck genutzt werden. Zu diesen Angaben k\\u00f6nnen z.B. betrachtete Inhalte, besuchte Webseiten und dort genutzte Elemente und technische Angaben, wie der verwendete Browser, das verwendete Computersystem sowie Angaben zu Nutzungszeiten geh\\u00f6ren. Sofern Nutzer in die Erhebung ihrer Standortdaten eingewilligt haben, k\\u00f6nnen je nach Anbieter auch diese verarbeitet werden.<\\\/p>\\n\n\n<p>Es werden ebenfalls die IP-Adressen der Nutzer gespeichert. Jedoch nutzen wir ein IP-Masking-Verfahren (d.h., Pseudonymisierung durch K\\u00fcrzung der IP-Adresse) zum Schutz der Nutzer. Generell werden die im Rahmen von Webanalyse, A\\\/B-Testings und Optimierung keine Klardaten der Nutzer (wie z.B. E-Mail-Adressen oder Namen) gespeichert, sondern Pseudonyme. D.h., wir als auch die Anbieter der eingesetzten Software kennen nicht die tats\\u00e4chliche Identit\\u00e4t der Nutzer, sondern nur den f\\u00fcr Zwecke der jeweiligen Verfahren in deren Profilen gespeicherten Angaben.<\\\/p>\\n\n\n<p><strong>Hinweise zu Rechtsgrundlagen:<\\\/strong> Sofern wir die Nutzer um deren Einwilligung in den Einsatz der Drittanbieter bitten, ist die Rechtsgrundlage der Verarbeitung von Daten die Einwilligung. Ansonsten werden die Daten der Nutzer auf Grundlage unserer berechtigten Interessen (d.h. Interesse an effizienten, wirtschaftlichen und empf\\u00e4ngerfreundlichen Leistungen) verarbeitet. In diesem Zusammenhang m\\u00f6chten wir Sie auch auf die Informationen zur Verwendung von Cookies in dieser Datenschutzerkl\\u00e4rung hinweisen.<\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>Verarbeitete Datenarten:<\\\/strong> Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\\\/Kommunikationsdaten (z.B. Ger\\u00e4te-Informationen, IP-Adressen).<\\\/li>\\n\n\n<li><strong>Betroffene Personen:<\\\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\\\/li>\\n\n\n<li><strong>Zwecke der Verarbeitung:<\\\/strong> Reichweitenmessung (z.B. Zugriffsstatistiken, Erkennung wiederkehrender Besucher), Profile mit nutzerbezogenen Informationen (Erstellen von Nutzerprofilen).<\\\/li>\\n\n\n<li><strong>Sicherheitsma\\u00dfnahmen:<\\\/strong> IP-Masking (Pseudonymisierung der IP-Adresse).<\\\/li>\\n\n\n<li><strong>Rechtsgrundlagen:<\\\/strong> Einwilligung (Art. 6 Abs. 1 S. 1 lit. a. DSGVO), Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO).<\\\/li>\\n<\\\/ul>\\n\n\n<p><strong>Eingesetzte Dienste und Diensteanbieter:<\\\/strong><\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>Google Analytics:<\\\/strong> Reichweitenmessung und Webanalyse; Dienstanbieter: Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irland, Mutterunternehmen: Google LLC, 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA; Website: <a href=\\\"https:\\\/\\\/marketingplatform.google.com\\\/intl\\\/de\\\/about\\\/analytics\\\/\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/marketingplatform.google.com\\\/intl\\\/de\\\/about\\\/analytics\\\/<\\\/a>; Datenschutzerkl\\u00e4rung: <a href=\\\"https:\\\/\\\/policies.google.com\\\/privacy\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/policies.google.com\\\/privacy<\\\/a>.<\\\/li>\\n<\\\/ul>\\n\n\n<h2 id=\\\"m136\\\">Pr\\u00e4senzen in sozialen Netzwerken (Social Media)<\\\/h2>\\n\n\n<p>Wir unterhalten Onlinepr\\u00e4senzen innerhalb sozialer Netzwerke und verarbeiten in diesem Rahmen Daten der Nutzer, um mit den dort aktiven Nutzern zu kommunizieren oder um Informationen \\u00fcber uns anzubieten.<\\\/p>\\n\n\n<p>Wir weisen darauf hin, dass dabei Daten der Nutzer au\\u00dferhalb des Raumes der Europ\\u00e4ischen Union verarbeitet werden k\\u00f6nnen. Hierdurch k\\u00f6nnen sich f\\u00fcr die Nutzer Risiken ergeben, weil so z.B. die Durchsetzung der Rechte der Nutzer erschwert werden k\\u00f6nnte.<\\\/p>\\n\n\n<p>Ferner werden die Daten der Nutzer innerhalb sozialer Netzwerke im Regelfall f\\u00fcr Marktforschungs- und Werbezwecke verarbeitet. So k\\u00f6nnen z.B. anhand des Nutzungsverhaltens und sich daraus ergebender Interessen der Nutzer Nutzungsprofile erstellt werden. Die Nutzungsprofile k\\u00f6nnen wiederum verwendet werden, um z.B. Werbeanzeigen innerhalb und au\\u00dferhalb der Netzwerke zu schalten, die mutma\\u00dflich den Interessen der Nutzer entsprechen. Zu diesen Zwecken werden im Regelfall Cookies auf den Rechnern der Nutzer gespeichert, in denen das Nutzungsverhalten und die Interessen der Nutzer gespeichert werden. Ferner k\\u00f6nnen in den Nutzungsprofilen auch Daten unabh\\u00e4ngig der von den Nutzern verwendeten Ger\\u00e4te gespeichert werden (insbesondere, wenn die Nutzer Mitglieder der jeweiligen Plattformen sind und bei diesen eingeloggt sind).<\\\/p>\\n\n\n<p>F\\u00fcr eine detaillierte Darstellung der jeweiligen Verarbeitungsformen und der Widerspruchsm\\u00f6glichkeiten (Opt-Out) verweisen wir auf die Datenschutzerkl\\u00e4rungen und Angaben der Betreiber der jeweiligen Netzwerke.<\\\/p>\\n\n\n<p>Auch im Fall von Auskunftsanfragen und der Geltendmachung von Betroffenenrechten weisen wir darauf hin, dass diese am effektivsten bei den Anbietern geltend gemacht werden k\\u00f6nnen. Nur die Anbieter haben jeweils Zugriff auf die Daten der Nutzer und k\\u00f6nnen direkt entsprechende Ma\\u00dfnahmen ergreifen und Ausk\\u00fcnfte geben. Sollten Sie dennoch Hilfe ben\\u00f6tigen, dann k\\u00f6nnen Sie sich an uns wenden.<\\\/p>\\n\n\n<p><strong>Facebook<\\\/strong>: Wir sind gemeinsam mit Facebook Irland Ltd. f\\u00fcr die Erhebung (jedoch nicht die weitere Verarbeitung) von Daten der Besucher unserer Facebook-Seite (sog. \\u201eFanpage\\u201c) verantwortlich. Zu diesen Daten geh\\u00f6ren Informationen zu den Arten von Inhalten, die Nutzer sich ansehen oder mit denen sie interagieren, oder die von ihnen vorgenommenen Handlungen (siehe unter \\u201eVon dir und anderen get\\u00e4tigte und bereitgestellte Dinge\\u201c in der Facebook-Datenrichtlinie: <a href=\\\"https:\\\/\\\/www.facebook.com\\\/policy\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.facebook.com\\\/policy<\\\/a>), sowie Informationen \\u00fcber die von den Nutzern genutzten Ger\\u00e4te (z. B. IP-Adressen, Betriebssystem, Browsertyp, Spracheinstellungen, Cookie-Daten; siehe unter \\u201eGer\\u00e4teinformationen\\u201c in der Facebook-Datenrichtlinie-erkl\\u00e4rung: <a href=\\\"https:\\\/\\\/www.facebook.com\\\/policy\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.facebook.com\\\/policy<\\\/a>). Wie in der Facebook-Datenrichtlinie unter \\u201eWie verwenden wir diese Informationen?\\u201c erl\\u00e4utert, erhebt und verwendet Facebook Informationen auch, um Analysedienste, so genannte \\u201eSeiten-Insights\\u201c, f\\u00fcr Seitenbetreiber bereitzustellen, damit diese Erkenntnisse dar\\u00fcber erhalten, wie Personen mit ihren Seiten und mit den mit ihnen verbundenen Inhalten interagieren. Wir haben mit Facebook eine spezielle Vereinbarung abgeschlossen (\\u201eInformationen zu Seiten-Insights\\u201c, <a href=\\\"https:\\\/\\\/www.facebook.com\\\/legal\\\/terms\\\/page_controller_addendum\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.facebook.com\\\/legal\\\/terms\\\/page_controller_addendum<\\\/a>), in der insbesondere geregelt wird, welche Sicherheitsma\\u00dfnahmen Facebook beachten muss und in der Facebook sich bereit erkl\\u00e4rt hat die Betroffenenrechte zu erf\\u00fcllen (d. h. Nutzer k\\u00f6nnen z. B. Ausk\\u00fcnfte oder L\\u00f6schungsanfragen direkt an Facebook richten). Die Rechte der Nutzer (insbesondere auf Auskunft, L\\u00f6schung, Widerspruch und Beschwerde bei zust\\u00e4ndiger Aufsichtsbeh\\u00f6rde), werden durch die Vereinbarungen mit Facebook nicht eingeschr\\u00e4nkt. Weitere Hinweise finden sich in den \\u201eInformationen zu Seiten-Insights\\u201c (<a href=\\\"https:\\\/\\\/www.facebook.com\\\/legal\\\/terms\\\/information_about_page_insights_data\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.facebook.com\\\/legal\\\/terms\\\/information_about_page_insights_data<\\\/a>).<\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>Verarbeitete Datenarten:<\\\/strong> Kontaktdaten (z.B. E-Mail, Telefonnummern), Inhaltsdaten (z.B. Eingaben in Onlineformularen), Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\\\/Kommunikationsdaten (z.B. Ger\\u00e4te-Informationen, IP-Adressen).<\\\/li>\\n\n\n<li><strong>Betroffene Personen:<\\\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\\\/li>\\n\n\n<li><strong>Zwecke der Verarbeitung:<\\\/strong> Kontaktanfragen und Kommunikation, Feedback (z.B. Sammeln von Feedback via Online-Formular), Marketing.<\\\/li>\\n\n\n<li><strong>Rechtsgrundlagen:<\\\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO).<\\\/li>\\n<\\\/ul>\\n\n\n<p><strong>Eingesetzte Dienste und Diensteanbieter:<\\\/strong><\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>Instagram:<\\\/strong> Soziales Netzwerk; Dienstanbieter: Instagram Inc., 1601 Willow Road, Menlo Park, CA, 94025, USA, Mutterunternehmen: Facebook, 1 Hacker Way, Menlo Park, CA 94025, USA; Website: <a href=\\\"https:\\\/\\\/www.instagram.com\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.instagram.com<\\\/a>; Datenschutzerkl\\u00e4rung: <a href=\\\"https:\\\/\\\/instagram.com\\\/about\\\/legal\\\/privacy\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/instagram.com\\\/about\\\/legal\\\/privacy<\\\/a>.<\\\/li>\\n\n\n<li><strong>Facebook:<\\\/strong> Soziales Netzwerk; Dienstanbieter: Facebook Ireland Ltd., 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irland, Mutterunternehmen: Facebook, 1 Hacker Way, Menlo Park, CA 94025, USA; Website: <a href=\\\"https:\\\/\\\/www.facebook.com\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.facebook.com<\\\/a>; Datenschutzerkl\\u00e4rung: <a href=\\\"https:\\\/\\\/www.facebook.com\\\/about\\\/privacy\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.facebook.com\\\/about\\\/privacy<\\\/a>; Widerspruchsm\\u00f6glichkeit (Opt-Out): Einstellungen f\\u00fcr Werbeanzeigen: <a href=\\\"https:\\\/\\\/www.facebook.com\\\/adpreferences\\\/ad_settings\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.facebook.com\\\/adpreferences\\\/ad_settings<\\\/a>.<\\\/li>\\n<\\\/ul>\\n\n\n<h2 id=\\\"m328\\\">Plugins und eingebettete Funktionen sowie Inhalte<\\\/h2>\\n\n\n<p>Wir binden in unser Onlineangebot Funktions- und Inhaltselemente ein, die von den Servern ihrer jeweiligen Anbieter (nachfolgend bezeichnet als \\u201eDrittanbieter\\u201d) bezogen werden. Dabei kann es sich zum Beispiel um Grafiken, Videos oder Stadtpl\\u00e4ne handeln (nachfolgend einheitlich bezeichnet als \\u201eInhalte\\u201d).<\\\/p>\\n\n\n<p>Die Einbindung setzt immer voraus, dass die Drittanbieter dieser Inhalte die IP-Adresse der Nutzer verarbeiten, da sie ohne die IP-Adresse die Inhalte nicht an deren Browser senden k\\u00f6nnten. Die IP-Adresse ist damit f\\u00fcr die Darstellung dieser Inhalte oder Funktionen erforderlich. Wir bem\\u00fchen uns, nur solche Inhalte zu verwenden, deren jeweilige Anbieter die IP-Adresse lediglich zur Auslieferung der Inhalte verwenden. Drittanbieter k\\u00f6nnen ferner sogenannte Pixel-Tags (unsichtbare Grafiken, auch als \\u201eWeb Beacons\\u201c bezeichnet) f\\u00fcr statistische oder Marketingzwecke verwenden. Durch die \\u201ePixel-Tags\\u201c k\\u00f6nnen Informationen, wie der Besucherverkehr auf den Seiten dieser Webseite, ausgewertet werden. Die pseudonymen Informationen k\\u00f6nnen ferner in Cookies auf dem Ger\\u00e4t der Nutzer gespeichert werden und unter anderem technische Informationen zum Browser und zum Betriebssystem, zu verweisenden Webseiten, zur Besuchszeit sowie weitere Angaben zur Nutzung unseres Onlineangebotes enthalten als auch mit solchen Informationen aus anderen Quellen verbunden werden.<\\\/p>\\n\n\n<p><strong>Hinweise zu Rechtsgrundlagen:<\\\/strong> Sofern wir die Nutzer um deren Einwilligung in den Einsatz der Drittanbieter bitten, ist die Rechtsgrundlage der Verarbeitung von Daten die Einwilligung. Ansonsten werden die Daten der Nutzer auf Grundlage unserer berechtigten Interessen (d.h. Interesse an effizienten, wirtschaftlichen und empf\\u00e4ngerfreundlichen Leistungen) verarbeitet. In diesem Zusammenhang m\\u00f6chten wir Sie auch auf die Informationen zur Verwendung von Cookies in dieser Datenschutzerkl\\u00e4rung hinweisen.<\\\/p>\\n\n\n<p><strong>Facebook-Plugins und -Inhalte<\\\/strong>: Wir sind gemeinsam mit Facebook Irland Ltd. f\\u00fcr die Erhebung oder den Erhalt im Rahmen einer \\u00dcbermittlung (jedoch nicht die weitere Verarbeitung) von \\u201eEvent-Daten\\u201c, die Facebook mittels der Facebook-Social-Plugins (und Einbettungsfunktionen f\\u00fcr Inhalte), die auf unserem Onlineangebot ausgef\\u00fchrt werden, erhebt oder im Rahmen einer \\u00dcbermittlung zu folgenden Zwecken erh\\u00e4lt, gemeinsam verantwortlich: a) Anzeige von Inhalten sowie Werbeinformationen, die den mutma\\u00dflichen Interessen der Nutzer entsprechen; b) Zustellung kommerzieller und transaktionsbezogener Nachrichten (z. B. Ansprache von Nutzern via Facebook-Messenger); c) Verbesserung der Anzeigenauslieferung und Personalisierung von Funktionen und Inhalten (z. B. Verbesserung der Erkennung, welche Inhalte oder Werbeinformationen mutma\\u00dflich den Interessen der Nutzer entsprechen). Wir haben mit Facebook eine spezielle Vereinbarung abgeschlossen (\\u201eZusatz f\\u00fcr Verantwortliche\\u201c, <a href=\\\"https:\\\/\\\/www.facebook.com\\\/legal\\\/controller_addendum\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.facebook.com\\\/legal\\\/controller_addendum<\\\/a>), in der insbesondere geregelt wird, welche Sicherheitsma\\u00dfnahmen Facebook beachten muss (<a href=\\\"https:\\\/\\\/www.facebook.com\\\/legal\\\/terms\\\/data_security_terms\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.facebook.com\\\/legal\\\/terms\\\/data_security_terms<\\\/a>) und in der Facebook sich bereit erkl\\u00e4rt hat die Betroffenenrechte zu erf\\u00fcllen (d. h. Nutzer k\\u00f6nnen z. B. Ausk\\u00fcnfte oder L\\u00f6schungsanfragen direkt an Facebook richten). Hinweis: Wenn Facebook uns Messwerte, Analysen und Berichte bereitstellt (die aggregiert sind, d. h. keine Angaben zu einzelnen Nutzern erhalten und f\\u00fcr uns anonym sind), dann erfolgt diese Verarbeitung nicht im Rahmen der gemeinsamen Verantwortlichkeit, sondern auf Grundlage eines Auftragsverarbeitungsvertrages (\\u201eDatenverarbeitungsbedingungen \\u201e, <a href=\\\"https:\\\/\\\/www.facebook.com\\\/legal\\\/terms\\\/dataprocessing\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.facebook.com\\\/legal\\\/terms\\\/dataprocessing<\\\/a>) , der \\u201eDatensicherheitsbedingungen\\u201c (<a href=\\\"https:\\\/\\\/www.facebook.com\\\/legal\\\/terms\\\/data_security_terms\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.facebook.com\\\/legal\\\/terms\\\/data_security_terms<\\\/a>) sowie im Hinblick auf die Verarbeitung in den USA auf Grundlage von Standardvertragsklauseln (\\u201eFacebook-EU-Daten\\u00fcbermittlungszusatz, <a href=\\\"https:\\\/\\\/www.facebook.com\\\/legal\\\/EU_data_transfer_addendum\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.facebook.com\\\/legal\\\/EU_data_transfer_addendum<\\\/a>). Die Rechte der Nutzer (insbesondere auf Auskunft, L\\u00f6schung, Widerspruch und Beschwerde bei zust\\u00e4ndiger Aufsichtsbeh\\u00f6rde), werden durch die Vereinbarungen mit Facebook nicht eingeschr\\u00e4nkt.<\\\/p>\\n\n\n<p><strong>Instagram-Plugins und -Inhalte<\\\/strong>: Wir sind gemeinsam mit Facebook Irland Ltd. f\\u00fcr die Erhebung oder den Erhalt im Rahmen einer \\u00dcbermittlung (jedoch nicht die weitere Verarbeitung) von \\u201eEvent-Daten\\u201c, die Facebook mittels Funktionen von Instagram (z. B. Einbettungsfunktionen f\\u00fcr Inhalte), die auf unserem Onlineangebot ausgef\\u00fchrt werden, erhebt oder im Rahmen einer \\u00dcbermittlung zu folgenden Zwecken erh\\u00e4lt, gemeinsam verantwortlich: a) Anzeige von Inhalten sowie Werbeinformationen, die den mutma\\u00dflichen Interessen der Nutzer entsprechen; b) Zustellung kommerzieller und transaktionsbezogener Nachrichten (z. B. Ansprache von Nutzern via Facebook-Messenger); c) Verbesserung der Anzeigenauslieferung und Personalisierung von Funktionen und Inhalten (z. B. Verbesserung der Erkennung, welche Inhalte oder Werbeinformationen mutma\\u00dflich den Interessen der Nutzer entsprechen). Wir haben mit Facebook eine spezielle Vereinbarung abgeschlossen (\\u201eZusatz f\\u00fcr Verantwortliche\\u201c, <a href=\\\"https:\\\/\\\/www.facebook.com\\\/legal\\\/controller_addendum\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.facebook.com\\\/legal\\\/controller_addendum<\\\/a>), in der insbesondere geregelt wird, welche Sicherheitsma\\u00dfnahmen Facebook beachten muss (<a href=\\\"https:\\\/\\\/www.facebook.com\\\/legal\\\/terms\\\/data_security_terms\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.facebook.com\\\/legal\\\/terms\\\/data_security_terms<\\\/a>) und in der Facebook sich bereit erkl\\u00e4rt hat die Betroffenenrechte zu erf\\u00fcllen (d. h. Nutzer k\\u00f6nnen z. B. Ausk\\u00fcnfte oder L\\u00f6schungsanfragen direkt an Facebook richten). Hinweis: Wenn Facebook uns Messwerte, Analysen und Berichte bereitstellt (die aggregiert sind, d. h. keine Angaben zu einzelnen Nutzern erhalten und f\\u00fcr uns anonym sind), dann erfolgt diese Verarbeitung nicht im Rahmen der gemeinsamen Verantwortlichkeit, sondern auf Grundlage eines Auftragsverarbeitungsvertrages (\\u201eDatenverarbeitungsbedingungen \\u201e, <a href=\\\"https:\\\/\\\/www.facebook.com\\\/legal\\\/terms\\\/dataprocessing\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.facebook.com\\\/legal\\\/terms\\\/dataprocessing<\\\/a>) , der \\u201eDatensicherheitsbedingungen\\u201c (<a href=\\\"https:\\\/\\\/www.facebook.com\\\/legal\\\/terms\\\/data_security_terms\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.facebook.com\\\/legal\\\/terms\\\/data_security_terms<\\\/a>) sowie im Hinblick auf die Verarbeitung in den USA auf Grundlage von Standardvertragsklauseln (\\u201eFacebook-EU-Daten\\u00fcbermittlungszusatz, <a href=\\\"https:\\\/\\\/www.facebook.com\\\/legal\\\/EU_data_transfer_addendum\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.facebook.com\\\/legal\\\/EU_data_transfer_addendum<\\\/a>). Die Rechte der Nutzer (insbesondere auf Auskunft, L\\u00f6schung, Widerspruch und Beschwerde bei zust\\u00e4ndiger Aufsichtsbeh\\u00f6rde), werden durch die Vereinbarungen mit Facebook nicht eingeschr\\u00e4nkt.<\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>Verarbeitete Datenarten:<\\\/strong> Nutzungsdaten (z.B. besuchte Webseiten, Interesse an Inhalten, Zugriffszeiten), Meta-\\\/Kommunikationsdaten (z.B. Ger\\u00e4te-Informationen, IP-Adressen), Event-Daten (Facebook) (\\u201eEvent-Daten\\u201c sind Daten, die z. B. via Facebook-Pixel (via Apps oder auf anderen Wegen) von uns an Facebook \\u00fcbermittelt werden k\\u00f6nnen und sich auf Personen oder deren Handlungen beziehen; Zu den Daten geh\\u00f6ren z. B. Angaben \\u00fcber Besuche auf Websites, Interaktionen mit Inhalten, Funktionen, Installationen von Apps, K\\u00e4ufe von Produkten, etc.; die Event-Daten werden zwecks Bildung von Zielgruppen f\\u00fcr Inhalte und Werbeinformationen (Custom Audiences) verarbeitet; Event Daten beinhalten nicht die eigentlichen Inhalte (wie z. B. verfasste Kommentare), keine Login-Informationen und keine Kontaktinformationen (also keine Namen, E-Mail-Adressen und Telefonnummern). Event Daten werden durch Facebook nach maximal zwei Jahren gel\\u00f6scht, die aus ihnen gebildeten Zielgruppen mit der L\\u00f6schung unseres Facebook-Kontos), Bestandsdaten (z.B. Namen, Adressen), Kontaktdaten (z.B. E-Mail, Telefonnummern), Inhaltsdaten (z.B. Eingaben in Onlineformularen).<\\\/li>\\n\n\n<li><strong>Betroffene Personen:<\\\/strong> Nutzer (z.B. Webseitenbesucher, Nutzer von Onlinediensten).<\\\/li>\\n\n\n<li><strong>Zwecke der Verarbeitung:<\\\/strong> Bereitstellung unseres Onlineangebotes und Nutzerfreundlichkeit, Erbringung vertragliche Leistungen und Kundenservice, Marketing, Profile mit nutzerbezogenen Informationen (Erstellen von Nutzerprofilen).<\\\/li>\\n\n\n<li><strong>Rechtsgrundlagen:<\\\/strong> Berechtigte Interessen (Art. 6 Abs. 1 S. 1 lit. f. DSGVO), Einwilligung (Art. 6 Abs. 1 S. 1 lit. a. DSGVO), Vertragserf\\u00fcllung und vorvertragliche Anfragen (Art. 6 Abs. 1 S. 1 lit. b. DSGVO).<\\\/li>\\n<\\\/ul>\\n\n\n<p><strong>Eingesetzte Dienste und Diensteanbieter:<\\\/strong><\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>Facebook-Plugins und -Inhalte:<\\\/strong> Facebook Social Plugins und Inhalte \\u2013 Hierzu k\\u00f6nnen z.B. Inhalte wie Bilder, Videos oder Texte und Schaltfl\\u00e4chen geh\\u00f6ren, mit denen Nutzer Inhalte dieses Onlineangebotes innerhalb von Facebook teilen k\\u00f6nnen. Die Liste und das Aussehen der Facebook Social Plugins k\\u00f6nnen hier eingesehen werden: <a href=\\\"https:\\\/\\\/developers.facebook.com\\\/docs\\\/plugins\\\/\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/developers.facebook.com\\\/docs\\\/plugins\\\/<\\\/a>; Dienstanbieter: Facebook Ireland Ltd., 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irland, Mutterunternehmen: Facebook, 1 Hacker Way, Menlo Park, CA 94025, USA; Website: <a href=\\\"https:\\\/\\\/www.facebook.com\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.facebook.com<\\\/a>; Datenschutzerkl\\u00e4rung: <a href=\\\"https:\\\/\\\/www.facebook.com\\\/about\\\/privacy\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.facebook.com\\\/about\\\/privacy<\\\/a>; Widerspruchsm\\u00f6glichkeit (Opt-Out): Einstellungen f\\u00fcr Werbeanzeigen: <a href=\\\"https:\\\/\\\/www.facebook.com\\\/adpreferences\\\/ad_settings\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.facebook.com\\\/adpreferences\\\/ad_settings<\\\/a>.<\\\/li>\\n\n\n<li><strong>Instagram-Plugins und -Inhalte:<\\\/strong> Instagram Plugins und -Inhalte \\u2013 Hierzu k\\u00f6nnen z.B. Inhalte wie Bilder, Videos oder Texte und Schaltfl\\u00e4chen geh\\u00f6ren, mit denen Nutzer Inhalte dieses Onlineangebotes innerhalb von Instagram teilen k\\u00f6nnen. Dienstanbieter: <a href=\\\"https:\\\/\\\/www.instagram.com\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.instagram.com<\\\/a>, Instagram Inc., 1601 Willow Road, Menlo Park, CA, 94025, USA; Website: <a href=\\\"https:\\\/\\\/www.instagram.com\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.instagram.com<\\\/a>; Datenschutzerkl\\u00e4rung: <a href=\\\"https:\\\/\\\/instagram.com\\\/about\\\/legal\\\/privacy\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/instagram.com\\\/about\\\/legal\\\/privacy<\\\/a>.<\\\/li>\\n\n\n<li><strong>Soundcloud Music Player Widget:<\\\/strong> Soundcloud Music Player Widget; Dienstanbieter: SoundCloud Limited, Rheinsberger Str. 76\\\/77, 10115 Berlin, Deutschland; Website: <a href=\\\"https:\\\/\\\/soundcloud.com\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/soundcloud.com<\\\/a>; Datenschutzerkl\\u00e4rung: <a href=\\\"https:\\\/\\\/soundcloud.com\\\/pages\\\/privacy\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/soundcloud.com\\\/pages\\\/privacy<\\\/a>.<\\\/li>\\n\n\n<li><strong>YouTube-Videos:<\\\/strong> Videoinhalte; Dienstanbieter: Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irland, Mutterunternehmen: Google LLC, 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA; Website: <a href=\\\"https:\\\/\\\/www.youtube.com\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/www.youtube.com<\\\/a>; Datenschutzerkl\\u00e4rung: <a href=\\\"https:\\\/\\\/policies.google.com\\\/privacy\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/policies.google.com\\\/privacy<\\\/a>; Widerspruchsm\\u00f6glichkeit (Opt-Out): Opt-Out-Plugin: <a href=\\\"https:\\\/\\\/tools.google.com\\\/dlpage\\\/gaoptout?hl=de\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/tools.google.com\\\/dlpage\\\/gaoptout?hl=de<\\\/a>, Einstellungen f\\u00fcr die Darstellung von Werbeeinblendungen: <a href=\\\"https:\\\/\\\/adssettings.google.com\\\/authenticated\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\">https:\\\/\\\/adssettings.google.com\\\/authenticated<\\\/a>.<\\\/li>\\n<\\\/ul>\\n\n\n<h2 id=\\\"m12\\\">L\\u00f6schung von Daten<\\\/h2>\\n\n\n<p>Die von uns verarbeiteten Daten werden nach Ma\\u00dfgabe der gesetzlichen Vorgaben gel\\u00f6scht, sobald deren zur Verarbeitung erlaubten Einwilligungen widerrufen werden oder sonstige Erlaubnisse entfallen (z.B., wenn der Zweck der Verarbeitung dieser Daten entfallen ist oder sie f\\u00fcr den Zweck nicht erforderlich sind).<\\\/p>\\n\n\n<p>Sofern die Daten nicht gel\\u00f6scht werden, weil sie f\\u00fcr andere und gesetzlich zul\\u00e4ssige Zwecke erforderlich sind, wird deren Verarbeitung auf diese Zwecke beschr\\u00e4nkt. D.h., die Daten werden gesperrt und nicht f\\u00fcr andere Zwecke verarbeitet. Das gilt z.B. f\\u00fcr Daten, die aus handels- oder steuerrechtlichen Gr\\u00fcnden aufbewahrt werden m\\u00fcssen oder deren Speicherung zur Geltendmachung, Aus\\u00fcbung oder Verteidigung von Rechtsanspr\\u00fcchen oder zum Schutz der Rechte einer anderen nat\\u00fcrlichen oder juristischen Person erforderlich ist.<\\\/p>\\n\n\n<p>Im Rahmen unserer Datenschutzhinweise k\\u00f6nnen wir den Nutzern weitere Informationen zu der L\\u00f6schung sowie zu der Aufbewahrung von Daten mitteilen, die speziell f\\u00fcr die jeweiligen Verarbeitungsprozesses gelten.<\\\/p>\\n\n\n<h2 id=\\\"m15\\\">\\u00c4nderung und Aktualisierung der Datenschutzerkl\\u00e4rung<\\\/h2>\\n\n\n<p>Wir bitten Sie, sich regelm\\u00e4\\u00dfig \\u00fcber den Inhalt unserer Datenschutzerkl\\u00e4rung zu informieren. Wir passen die Datenschutzerkl\\u00e4rung an, sobald die \\u00c4nderungen der von uns durchgef\\u00fchrten Datenverarbeitungen dies erforderlich machen. Wir informieren Sie, sobald durch die \\u00c4nderungen eine Mitwirkungshandlung Ihrerseits (z.B. Einwilligung) oder eine sonstige individuelle Benachrichtigung erforderlich wird.<\\\/p>\\n\n\n<p>Sofern wir in dieser Datenschutzerkl\\u00e4rung Adressen und Kontaktinformationen von Unternehmen und Organisationen angeben, bitten wir zu beachten, dass die Adressen sich \\u00fcber die Zeit \\u00e4ndern k\\u00f6nnen und bitten die Angaben vor Kontaktaufnahme zu pr\\u00fcfen.<\\\/p>\\n\n\n<h2 id=\\\"m10\\\">Rechte der betroffenen Personen<\\\/h2>\\n\n\n<p>Ihnen stehen als Betroffene nach der DSGVO verschiedene Rechte zu, die sich insbesondere aus Art. 15 bis 21 DSGVO ergeben:<\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>Widerspruchsrecht: Sie haben das Recht, aus Gr\\u00fcnden, die sich aus Ihrer besonderen Situation ergeben, jederzeit gegen die Verarbeitung der Sie betreffenden personenbezogenen Daten, die aufgrund von Art. 6 Abs. 1 lit. e oder f DSGVO erfolgt, Widerspruch einzulegen; dies gilt auch f\\u00fcr ein auf diese Bestimmungen gest\\u00fctztes Profiling. Werden die Sie betreffenden personenbezogenen Daten verarbeitet, um Direktwerbung zu betreiben, haben Sie das Recht, jederzeit Widerspruch gegen die Verarbeitung der Sie betreffenden personenbezogenen Daten zum Zwecke derartiger Werbung einzulegen; dies gilt auch f\\u00fcr das Profiling, soweit es mit solcher Direktwerbung in Verbindung steht.<\\\/strong><\\\/li>\\n\n\n<li><strong>Widerrufsrecht bei Einwilligungen:<\\\/strong> Sie haben das Recht, erteilte Einwilligungen jederzeit zu widerrufen.<\\\/li>\\n\n\n<li><strong>Auskunftsrecht:<\\\/strong> Sie haben das Recht, eine Best\\u00e4tigung dar\\u00fcber zu verlangen, ob betreffende Daten verarbeitet werden und auf Auskunft \\u00fcber diese Daten sowie auf weitere Informationen und Kopie der Daten entsprechend den gesetzlichen Vorgaben.<\\\/li>\\n\n\n<li><strong>Recht auf Berichtigung:<\\\/strong> Sie haben entsprechend den gesetzlichen Vorgaben das Recht, die Vervollst\\u00e4ndigung der Sie betreffenden Daten oder die Berichtigung der Sie betreffenden unrichtigen Daten zu verlangen.<\\\/li>\\n\n\n<li><strong>Recht auf L\\u00f6schung und Einschr\\u00e4nkung der Verarbeitung:<\\\/strong> Sie haben nach Ma\\u00dfgabe der gesetzlichen Vorgaben das Recht, zu verlangen, dass Sie betreffende Daten unverz\\u00fcglich gel\\u00f6scht werden, bzw. alternativ nach Ma\\u00dfgabe der gesetzlichen Vorgaben eine Einschr\\u00e4nkung der Verarbeitung der Daten zu verlangen.<\\\/li>\\n\n\n<li><strong>Recht auf Daten\\u00fcbertragbarkeit:<\\\/strong> Sie haben das Recht, Sie betreffende Daten, die Sie uns bereitgestellt haben, nach Ma\\u00dfgabe der gesetzlichen Vorgaben in einem strukturierten, g\\u00e4ngigen und maschinenlesbaren Format zu erhalten oder deren \\u00dcbermittlung an einen anderen Verantwortlichen zu fordern.<\\\/li>\\n\n\n<li><strong>Beschwerde bei Aufsichtsbeh\\u00f6rde:<\\\/strong> Entsprechend den gesetzlichen Vorgaben und unbeschadet eines anderweitigen verwaltungsrechtlichen oder gerichtlichen Rechtsbehelfs, haben Sie ferner das Recht, bei einer Datenschutzaufsichtsbeh\\u00f6rde, insbesondere einer Aufsichtsbeh\\u00f6rde im Mitgliedstaat, in dem Sie sich gew\\u00f6hnlich aufhalten, der Aufsichtsbeh\\u00f6rde Ihres Arbeitsplatzes oder des Ortes des mutma\\u00dflichen Versto\\u00dfes, eine Beschwerde einzulegen, wenn Sie der Ansicht sei sollten, dass die Verarbeitung der Ihre Person betreffenden personenbezogenen Daten gegen die DSGVO verst\\u00f6\\u00dft.<\\\/li>\\n<\\\/ul>\\n\n\n<h2 id=\\\"m42\\\">Begriffsdefinitionen<\\\/h2>\\n\n\n<p>In diesem Abschnitt erhalten Sie eine \\u00dcbersicht \\u00fcber die in dieser Datenschutzerkl\\u00e4rung verwendeten Begrifflichkeiten. Viele der Begriffe sind dem Gesetz entnommen und vor allem im Art. 4 DSGVO definiert. Die gesetzlichen Definitionen sind verbindlich. Die nachfolgenden Erl\\u00e4uterungen sollen dagegen vor allem dem Verst\\u00e4ndnis dienen. Die Begriffe sind alphabetisch sortiert.<\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>IP-Masking:<\\\/strong> Als \\u201eIP-Masking\\u201d wird eine Methode bezeichnet, bei der das letzte Oktett, d.h., die letzten beiden Zahlen einer IP-Adresse, gel\\u00f6scht wird, damit die IP-Adresse nicht mehr der eindeutigen Identifizierung einer Person dienen kann. Daher ist das IP-Masking ein Mittel zur Pseudonymisierung von Verarbeitungsverfahren, insbesondere im Onlinemarketing<\\\/li>\\n\n\n<li><strong>Personenbezogene Daten:<\\\/strong> \\u201ePersonenbezogene Daten\\u201c sind alle Informationen, die sich auf eine identifizierte oder identifizierbare nat\\u00fcrliche Person (im Folgenden \\u201ebetroffene Person\\u201c) beziehen; als identifizierbar wird eine nat\\u00fcrliche Person angesehen, die direkt oder indirekt, insbesondere mittels Zuordnung zu einer Kennung wie einem Namen, zu einer Kennnummer, zu Standortdaten, zu einer Online-Kennung (z.B. Cookie) oder zu einem oder mehreren besonderen Merkmalen identifiziert werden kann, die Ausdruck der physischen, physiologischen, genetischen, psychischen, wirtschaftlichen, kulturellen oder sozialen Identit\\u00e4t dieser nat\\u00fcrlichen Person sind.<\\\/li>\\n\n\n<li><strong>Profile mit nutzerbezogenen Informationen:<\\\/strong> Die Verarbeitung von \\u201eProfilen mit nutzerbezogenen Informationen\\u201c, bzw. kurz \\u201eProfilen\\u201c umfasst jede Art der automatisierten Verarbeitung personenbezogener Daten, die darin besteht, dass diese personenbezogenen Daten verwendet werden, um bestimmte pers\\u00f6nliche Aspekte, die sich auf eine nat\\u00fcrliche Person beziehen (je nach Art der Profilbildung k\\u00f6nnen dazu unterschiedliche Informationen betreffend die Demographie, Verhalten und Interessen, wie z.B. die Interaktion mit Webseiten und deren Inhalten, etc.) zu analysieren, zu bewerten oder, um sie vorherzusagen (z.B. die Interessen an bestimmten Inhalten oder Produkten, das Klickverhalten auf einer Webseite oder den Aufenthaltsort). Zu Zwecken des Profilings werden h\\u00e4ufig Cookies und Web-Beacons eingesetzt.<\\\/li>\\n\n\n<li><strong>Reichweitenmessung:<\\\/strong> Die Reichweitenmessung (auch als Web Analytics bezeichnet) dient der Auswertung der Besucherstr\\u00f6me eines Onlineangebotes und kann das Verhalten oder Interessen der Besucher an bestimmten Informationen, wie z.B. Inhalten von Webseiten, umfassen. Mit Hilfe der Reichweitenanalyse k\\u00f6nnen Webseiteninhaber z.B. erkennen, zu welcher Zeit Besucher ihre Webseite besuchen und f\\u00fcr welche Inhalte sie sich interessieren. Dadurch k\\u00f6nnen sie z.B. die Inhalte der Webseite besser an die Bed\\u00fcrfnisse ihrer Besucher anpassen. Zu Zwecken der Reichweitenanalyse werden h\\u00e4ufig pseudonyme Cookies und Web-Beacons eingesetzt, um wiederkehrende Besucher zu erkennen und so genauere Analysen zur Nutzung eines Onlineangebotes zu erhalten.<\\\/li>\\n\n\n<li><strong>Verantwortlicher:<\\\/strong> Als \\u201eVerantwortlicher\\u201c wird die nat\\u00fcrliche oder juristische Person, Beh\\u00f6rde, Einrichtung oder andere Stelle, die allein oder gemeinsam mit anderen \\u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten entscheidet, bezeichnet.<\\\/li>\\n\n\n<li><strong>Verarbeitung:<\\\/strong> \\u201eVerarbeitung\\u201c ist jeder mit oder ohne Hilfe automatisierter Verfahren ausgef\\u00fchrte Vorgang oder jede solche Vorgangsreihe im Zusammenhang mit personenbezogenen Daten. Der Begriff reicht weit und umfasst praktisch jeden Umgang mit Daten, sei es das Erheben, das Auswerten, das Speichern, das \\u00dcbermitteln oder das L\\u00f6schen.<\\\/li>\\n<\\\/ul>\\n\n\n<figure class=\\\"wp-block-image\\\"><a href=\\\"https:\\\/\\\/datenschutz-generator.de\\\/?l=de\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\" class=\\\"customize-unpreviewable\\\"><img src=\\\"https:\\\/\\\/datenschutz-generator.de\\\/wp-content\\\/plugins\\\/ts-dsg\\\/images\\\/dsg-seal\\\/dsg-seal-pp-de.png\\\" alt=\\\"Rechtstext von Dr. Schwenke - f\\u00fcr weitere Informationen bitte anklicken.\\\" \\\/><\\\/a><\\\/figure>\\n<\\\/div>\",\"content_en_us\":\"\n\n<h2>Introduction<\\\/h2>\\n\n\n<p>With the following privacy policy, we would like to inform you about the types of your personal data (hereinafter also referred to as \\\"data\\\") that we process, for what purposes, and to what extent. The privacy policy applies to all processing of personal data carried out by us, both in the context of providing our services and in particular on our websites, in mobile applications, and within external online presences, such as our social media profiles (hereinafter collectively referred to as \\\"online offering\\\").<\\\/p>\\n\n\n<p>The terms used are not gender-specific.<\\\/p>\\n\n\n<p>Status: April 20, 2021<\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<h2>Table of Contents<\\\/h2>\\n\n\n<ul>\\n\n\n<li>Introduction<\\\/li>\\n\n\n<li>Controller<\\\/li>\\n\n\n<li>Overview of Processing Activities<\\\/li>\\n\n\n<li>Applicable Legal Bases<\\\/li>\\n\n\n<li>Security Measures<\\\/li>\\n\n\n<li>Use of Cookies<\\\/li>\\n\n\n<li>Provision of Online Offering and Web Hosting<\\\/li>\\n\n\n<li>Blogs and Publication Media<\\\/li>\\n\n\n<li>Cloud Services<\\\/li>\\n\n\n<li>Newsletter and Electronic Notifications<\\\/li>\\n\n\n<li>Web Analysis, Monitoring, and Optimization<\\\/li>\\n\n\n<li>Presence on Social Networks (Social Media)<\\\/li>\\n\n\n<li>Plugins and Embedded Functions and Content<\\\/li>\\n\n\n<li>Deletion of Data<\\\/li>\\n\n\n<li>Changes and Updates to the Privacy Policy<\\\/li>\\n\n\n<li>Rights of Data Subjects<\\\/li>\\n\n\n<li>Definitions of Terms<\\\/li>\\n<\\\/ul>\\n\n\n<p><\\\/p>\\n\n\n<h2>Controller<\\\/h2>\\n\n\n<p>Antiquit\\u00e4ten im Rathaus<\\\/p>\\n\n\n<p>Peter Vogt<\\\/p>\\n\n\n<p>Marienplatz 8<\\\/p>\\n\n\n<p>80331 Munich<\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<p>Authorized representative: Peter Vogt<\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<p>Email address: verkauf(a)fayence-steinzeug-vogt.de<\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<p>Telephone: 089 294132<\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<p>Imprint: https:\\\/\\\/fayence-steinzeug-vogt.de\\\/impressum\\\/<\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<h2>Overview of Processing Activities<\\\/h2>\\n\n\n<p>The following overview summarizes the types of data processed and the purposes of their processing and refers to the data subjects.<\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<p><strong>Types of Data Processed<\\\/strong><\\\/p>\\n\n\n<ul>\\n\n\n<li>Event Data (Facebook) (\\\"Event data\\\" is data that can be transmitted by us to Facebook, for example via Facebook Pixel (via apps or other means), and relates to persons or their actions; The data includes, for example, information about visits to websites, interactions with content, functions, installations of apps, purchases of products, etc.; Event data is processed for the purpose of creating target groups for content and advertising information (Custom Audiences); Event data does not include the actual content (such as comments written), no login information, and no contact information (i.e., no names, email addresses, and telephone numbers). Event data is deleted by Facebook after a maximum of two years, the target groups formed from them with the deletion of our Facebook account).<\\\/li>\\n\n\n<li>Inventory data (e.g., names, addresses)<\\\/li>\\n\n\n<li>Content data (e.g., entries in online forms)<\\\/li>\\n\n\n<li>Contact data (e.g., email, telephone numbers)<\\\/li>\\n\n\n<li>Meta\\\/communication data (e.g., device information, IP addresses)<\\\/li>\\n\n\n<li>Usage data (e.g., websites visited, interest in content, access times)<\\\/li>\\n<\\\/ul>\\n\n\n<p><\\\/p>\\n\n\n<p><strong>Categories of Data Subjects<\\\/strong><\\\/p>\\n\n\n<ul>\\n\n\n<li>Employees (e.g., employees, applicants, former employees)<\\\/li>\\n\n\n<li>Prospective customers<\\\/li>\\n\n\n<li>Communication partners<\\\/li>\\n\n\n<li>Customers<\\\/li>\\n\n\n<li>Users (e.g., website visitors, users of online services)<\\\/li>\\n<\\\/ul>\\n\n\n<p><\\\/p>\\n\n\n<p><strong>Purposes of Processing<\\\/strong><\\\/p>\\n\n\n<ul>\\n\n\n<li>Provision of our online offering and user-friendliness<\\\/li>\\n\n\n<li>Office and organizational procedures<\\\/li>\\n\n\n<li>Direct marketing (e.g., by email or mail)<\\\/li>\\n\n\n<li>Feedback (e.g., collecting feedback via online form)<\\\/li>\\n\n\n<li>Marketing<\\\/li>\\n\n\n<li>Contact requests and communication<\\\/li>\\n\n\n<li>Profiles with user-related information (creation of user profiles)<\\\/li>\\n\n\n<li>Reach measurement (e.g., access statistics, recognition of returning visitors)<\\\/li>\\n\n\n<li>Security measures<\\\/li>\\n\n\n<li>Provision of contractual services and customer service<\\\/li>\\n<\\\/ul>\\n\n\n<p><\\\/p>\\n\n\n<h2>Applicable Legal Bases<\\\/h2>\\n\n\n<p>Below you will find an overview of the legal bases of the GDPR on which we base the processing of personal data. Please note that in addition to the provisions of the GDPR, national data protection regulations of your or our country of residence or domicile may apply. Should more specific legal bases be applicable in individual cases, we will inform you of these in the privacy policy.<\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<ul>\\n\n\n<li>Consent (Art. 6(1)(a) GDPR) \\u2013 The data subject has given consent to the processing of their personal data for one or more specific purposes.<\\\/li>\\n\n\n<li>Contract performance and pre-contractual inquiries (Art. 6(1)(b) GDPR) \\u2013 Processing is necessary for the performance of a contract to which the data subject is party or in order to take steps at the request of the data subject prior to entering into a contract.<\\\/li>\\n\n\n<li>Legitimate interests (Art. 6(1)(f) GDPR) \\u2013 Processing is necessary for the purposes of the legitimate interests pursued by the controller or by a third party, except where such interests are overridden by the interests or fundamental rights and freedoms of the data subject which require protection of personal data.<\\\/li>\\n<\\\/ul>\\n\n\n<p><\\\/p>\\n\n\n<p><strong>National Data Protection Regulations in Germany: <\\\/strong>In addition to the data protection regulations of the General Data Protection Regulation, national regulations on data protection apply in Germany. These include in particular the Federal Data Protection Act (Bundesdatenschutzgesetz \\u2013 BDSG). The BDSG contains special provisions on the right to information, the right to deletion, the right to object, the processing of special categories of personal data, processing for other purposes, and transmission as well as automated decision-making in individual cases, including profiling. Furthermore, it regulates data processing for the purposes of the employment relationship (\\u00a7 26 BDSG), particularly with regard to the establishment, implementation, or termination of employment relationships and the consent of employees. Furthermore, state data protection laws of the individual federal states may apply.<\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<h2>Security Measures<\\\/h2>\\n\n\n<p>We take appropriate technical and organizational measures in accordance with legal requirements, taking into account the state of the art, implementation costs, and the nature, scope, context, and purposes of processing, as well as the varying likelihood and severity of risks to the rights and freedoms of natural persons, in order to ensure a level of protection appropriate to the risk.<\\\/p>\\n\n\n<p>The measures include, in particular, ensuring the confidentiality, integrity, and availability of data by controlling physical and electronic access to the data as well as access to, input of, disclosure of, ensuring availability of, and segregation of the data. Furthermore, we have established procedures to ensure the exercise of data subject rights, deletion of data, and responses to data compromise. Furthermore, we already take the protection of personal data into account during the development or selection of hardware, software, and procedures in accordance with the principle of data protection, through technology design, and through data protection-friendly default settings.<\\\/p>\\n\n\n<p><strong>SSL Encryption (https): <\\\/strong>To protect your data transmitted via our online offering, we use SSL encryption. You can recognize such encrypted connections by the prefix https:\\\/\\\/ in the address bar of your browser.<\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<h2>Use of Cookies<\\\/h2>\\n\n\n<p>Cookies are text files that contain data from visited websites or domains and are stored by a browser on the user's computer. A cookie primarily serves to store information about a user during or after their visit within an online offering. Stored information may include, for example, language settings on a website, login status, a shopping cart, or the position at which a video was watched. The term cookies also includes other technologies that fulfill the same functions as cookies (e.g., when user information is stored using pseudonymous online identifiers, also referred to as \\\"user IDs\\\").<\\\/p>\\n\n\n<p>The following cookie types and functions are distinguished:<\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>Temporary cookies (also: session cookies): <\\\/strong>Temporary cookies are deleted at the latest after a user has left an online offering and closed their browser.<\\\/li>\\n\n\n<li><strong>Permanent cookies: <\\\/strong>Permanent cookies remain stored even after the browser is closed. For example, the login status can be saved or preferred content can be displayed directly when the user visits a website again. Likewise, user interests used for reach measurement or marketing purposes can be stored in such a cookie.<\\\/li>\\n\n\n<li><strong>First-party cookies: <\\\/strong>First-party cookies are set by us ourselves.<\\\/li>\\n\n\n<li><strong>Third-party cookies: <\\\/strong>Third-party cookies are mainly used by advertisers (so-called third parties) to process user information.<\\\/li>\\n\n\n<li><strong>Necessary (also: essential or strictly necessary) cookies: <\\\/strong>Cookies may be strictly necessary for the operation of a website (e.g., to store logins or other user inputs or for security reasons).<\\\/li>\\n\n\n<li><strong>Statistics, marketing, and personalization cookies: <\\\/strong>Furthermore, cookies are usually also used in reach measurement as well as when a user's interests or behavior (e.g., viewing certain content, using functions, etc.) are stored in a user profile on individual websites. Such profiles serve to show users, for example, content that corresponds to their potential interests. This procedure is also referred to as \\\"tracking\\\", i.e., tracking of users' potential interests. If we use cookies or \\\"tracking\\\" technologies, we will inform you separately in our privacy policy or when obtaining consent.<\\\/li>\\n<\\\/ul>\\n\n\n<p><\\\/p>\\n\n\n<p><strong>Information on legal bases: <\\\/strong>The legal basis on which we process your personal data using cookies depends on whether we ask you for consent. If this is the case and you consent to the use of cookies, the legal basis for processing your data is the declared consent. Otherwise, the data processed with the help of cookies is processed on the basis of our legitimate interests (e.g., in the business operation of our online offering and its improvement) or, if the use of cookies is necessary to fulfill our contractual obligations.<\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<p><strong>Storage duration: <\\\/strong>If we do not provide you with explicit information about the storage duration of permanent cookies (e.g., as part of a so-called cookie opt-in), please assume that the storage duration can be up to two years.<\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<p><strong>General information on revocation and objection (opt-out): <\\\/strong>Depending on whether processing is based on consent or legal permission, you have the option at any time to revoke consent given or to object to the processing of your data by cookie technologies (collectively referred to as \\\"opt-out\\\"). You can initially declare your objection by means of your browser settings, e.g., by deactivating the use of cookies (which may also limit the functionality of our online offering). An objection to the use of cookies for online marketing purposes can also be declared by means of a variety of services, especially in the case of tracking, via the websites https:\\\/\\\/optout.aboutads.info and https:\\\/\\\/www.youronlinechoices.com\\\/.<\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<h2>Provision of Online Offering and Web Hosting<\\\/h2>\\n\n\n<p>In order to be able to provide our online offering securely and efficiently, we use the services of one or more web hosting providers, from whose servers (or servers managed by them) the online offering can be accessed. For these purposes, we may use infrastructure and platform services, computing capacity, storage space, and database services as well as security services and technical maintenance services.<\\\/p>\\n\n\n<p>The data processed as part of the provision of the hosting offering may include all information concerning users of our online offering that arises in the context of use and communication. This regularly includes the IP address, which is necessary to deliver the content of online offerings to browsers, and all entries made within our online offering or from websites.<\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<p><strong>Types of data processed: <\\\/strong>Content data (e.g., entries in online forms); Usage data (e.g., websites visited, interest in content, access times); Meta\\\/communication data (e.g., device information, IP addresses).<\\\/p>\\n\n\n<p><strong>Data subjects: <\\\/strong>Users (e.g., website visitors, users of online services).<\\\/p>\\n\n\n<p><strong>Purposes of processing: <\\\/strong>Provision of our online offering and user-friendliness.<\\\/p>\\n\n\n<p><strong>Legal bases: <\\\/strong>Legitimate interests (Art. 6(1)(f) GDPR).<\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<h2>Deletion of Data<\\\/h2>\\n\n\n<p>The data processed by us will be deleted in accordance with legal requirements as soon as their consent permitted for processing is revoked or other permissions cease to apply (e.g., if the purpose of processing this data has ceased to apply or they are not required for the purpose).<\\\/p>\\n\n\n<p>If the data is not deleted because it is required for other and legally permissible purposes, its processing will be restricted to these purposes. That is, the data is blocked and not processed for other purposes. This applies, for example, to data that must be retained for commercial or tax law reasons or whose storage is necessary for the assertion, exercise, or defense of legal claims or for the protection of the rights of another natural or legal person.<\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<h2>Changes and Updates to the Privacy Policy<\\\/h2>\\n\n\n<p>We ask you to regularly inform yourself about the content of our privacy policy. We adapt the privacy policy as soon as the changes to the data processing carried out by us make this necessary. We will inform you as soon as the changes require your cooperation (e.g., consent) or other individual notification.<\\\/p>\\n\n\n<p>If we provide addresses and contact information of companies and organizations in this privacy policy, please note that the addresses may change over time and please check the information before contacting us.<\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<h2>Rights of Data Subjects<\\\/h2>\\n\n\n<p>As a data subject under the GDPR, you have various rights, which arise in particular from Articles 15 to 21 GDPR:<\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>Right to object: <\\\/strong>You have the right to object at any time, on grounds relating to your particular situation, to the processing of personal data concerning you which is based on Article 6(1)(e) or (f) GDPR; this also applies to profiling based on these provisions. If the personal data concerning you is processed for direct marketing purposes, you have the right to object at any time to the processing of personal data concerning you for the purpose of such marketing; this also applies to profiling insofar as it is related to such direct marketing.<\\\/li>\\n\n\n<li><strong>Right to withdraw consent: <\\\/strong>You have the right to withdraw consent given at any time.<\\\/li>\\n\n\n<li><strong>Right to information: <\\\/strong>You have the right to request confirmation as to whether data concerning you is being processed and to information about this data as well as further information and a copy of the data in accordance with legal requirements.<\\\/li>\\n\n\n<li><strong>Right to rectification: <\\\/strong>In accordance with legal requirements, you have the right to request the completion of data concerning you or the rectification of incorrect data concerning you.<\\\/li>\\n\n\n<li><strong>Right to deletion and restriction of processing: <\\\/strong>In accordance with legal requirements, you have the right to request that data concerning you be deleted immediately or, alternatively, in accordance with legal requirements, to request a restriction of the processing of the data.<\\\/li>\\n\n\n<li><strong>Right to data portability: <\\\/strong>You have the right to receive data concerning you which you have provided to us in a structured, commonly used, and machine-readable format in accordance with legal requirements or to request its transmission to another controller.<\\\/li>\\n\n\n<li><strong>Complaint to supervisory authority: <\\\/strong>In accordance with legal requirements and without prejudice to any other administrative or judicial remedy, you also have the right to lodge a complaint with a data protection supervisory authority, in particular a supervisory authority in the member state where you habitually reside, the supervisory authority of your workplace, or the place of the alleged infringement, if you believe that the processing of personal data concerning you violates the GDPR.<\\\/li>\\n<\\\/ul>\\n\n\n<p><\\\/p>\\n\n\n<h2>Definitions of Terms<\\\/h2>\\n\n\n<p>In this section, you will find an overview of the terminology used in this privacy policy. Many of the terms are taken from the law and defined primarily in Article 4 GDPR. The legal definitions are binding. The following explanations, on the other hand, are primarily intended to aid understanding. The terms are sorted alphabetically.<\\\/p>\\n\n\n<p><\\\/p>\\n\n\n<ul>\\n\n\n<li><strong>IP masking: <\\\/strong>\\\"IP masking\\\" refers to a method in which the last octet, i.e., the last two numbers of an IP address, is deleted so that the IP address can no longer be used for the unique identification of a person. Therefore, IP masking is a means of pseudonymization of processing procedures, especially in online marketing.<\\\/li>\\n\n\n<li><strong>Personal data: <\\\/strong>\\\"Personal data\\\" means any information relating to an identified or identifiable natural person (hereinafter \\\"data subject\\\"); an identifiable natural person is one who can be identified, directly or indirectly, in particular by reference to an identifier such as a name, an identification number, location data, an online identifier (e.g., cookie) or to one or more factors specific to the physical, physiological, genetic, mental, economic, cultural, or social identity of that natural person.<\\\/li>\\n\n\n<li><strong>Profiles with user-related information: <\\\/strong>The processing of \\\"profiles with user-related information\\\", or \\\"profiles\\\" for short, includes any type of automated processing of personal data that consists of using this personal data to analyze, evaluate, or predict certain personal aspects relating to a natural person (depending on the type of profiling, this may include different information concerning demographics, behavior, and interests, such as interaction with websites and their content, etc.). Cookies and web beacons are often used for profiling purposes.<\\\/li>\\n\n\n<li><strong>Reach measurement: <\\\/strong>Reach measurement (also referred to as web analytics) is used to evaluate the flow of visitors to an online offering and may include the behavior or interests of visitors in certain information, such as the content of websites. With the help of reach analysis, website owners can, for example, recognize at what time visitors visit their website and what content they are interested in. This allows them, for example, to better adapt the content of the website to the needs of their visitors. Pseudonymous cookies and web beacons are often used for the purposes of reach analysis to recognize returning visitors and thus obtain more precise analyses of the use of an online offering.<\\\/li>\\n\n\n<li><strong>Controller: <\\\/strong>The \\\"controller\\\" means the natural or legal person, public authority, agency, or other body which, alone or jointly with others, determines the purposes and means of the processing of personal data.<\\\/li>\\n\n\n<li><strong>Processing: <\\\/strong>\\\"Processing\\\" means any operation or set of operations which is performed on personal data or on sets of personal data, whether or not by automated means. The term is broad and includes practically any handling of data, be it collection, evaluation, storage, transmission, or deletion.<\\\/li>\\n<\\\/ul>\",\"margin\":\"default\"}}]}]}]}],\"version\":\"4.5.32\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Datenschutzerkl\u00e4rung Einleitung Mit der folgenden Datenschutzerkl\u00e4rung m\u00f6chten wir Sie dar\u00fcber aufkl\u00e4ren, welche Arten Ihrer personenbezogenen Daten (nachfolgend auch kurz als \u201eDaten\u201c bezeichnet) wir zu welchen Zwecken und in welchem Umfang verarbeiten. Die Datenschutzerkl\u00e4rung gilt f\u00fcr alle von uns durchgef\u00fchrten Verarbeitungen personenbezogener Daten, sowohl im Rahmen der Erbringung unserer Leistungen als auch insbesondere auf unseren Webseiten, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7144","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.fayence-steinzeug-vogt.de\/de\/wp-json\/wp\/v2\/pages\/7144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fayence-steinzeug-vogt.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fayence-steinzeug-vogt.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fayence-steinzeug-vogt.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fayence-steinzeug-vogt.de\/de\/wp-json\/wp\/v2\/comments?post=7144"}],"version-history":[{"count":10,"href":"https:\/\/www.fayence-steinzeug-vogt.de\/de\/wp-json\/wp\/v2\/pages\/7144\/revisions"}],"predecessor-version":[{"id":14212,"href":"https:\/\/www.fayence-steinzeug-vogt.de\/de\/wp-json\/wp\/v2\/pages\/7144\/revisions\/14212"}],"wp:attachment":[{"href":"https:\/\/www.fayence-steinzeug-vogt.de\/de\/wp-json\/wp\/v2\/media?parent=7144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}